{"id":188209,"date":"2015-03-13T00:00:00","date_gmt":"2015-03-12T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/symbole-triangle-noir-en-regard-des-specialites-qui-font-lobjet-dune-surveillance-supplementaire-liste-des-medicaments-mars-2015\/"},"modified":"2026-08-27T15:11:24","modified_gmt":"2026-08-27T13:11:24","slug":"symbole-triangle-noir-en-regard-des-specialites-qui-font-lobjet-dune-surveillance-supplementaire-liste-des-medicaments-mars-2015","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/symbole-triangle-noir-en-regard-des-specialites-qui-font-lobjet-dune-surveillance-supplementaire-liste-des-medicaments-mars-2015\/","title":{"rendered":"Symbole &lsquo;triangle noir&rsquo;\u00a0en regard des sp\u00e9cialit\u00e9s qui font l\u2019objet d\u2019une surveillance suppl\u00e9mentaire: liste des m\u00e9dicaments\u00a0mars 2015"},"content":{"rendered":"<div class='tekst'>\n<p>Afin d\u2019attirer davantage l\u2019attention sur les sp\u00e9cialit\u00e9s qui font l\u2019objet d\u2019une surveillance suppl\u00e9mentaire&#x002C; le symbole\u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='font-size:11px; height:10px; width:10px' \/>\u00a0est\u00a0plac\u00e9 dans le R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments en regard de ces sp\u00e9cialit\u00e9s [pour plus de d\u00e9tails&#x002C;\u00a0<a href='https:\/\/www.cbip.be\/Folia\/2013\/F40F07F.cfm'>voir Folia juillet-ao\u00fbt 2013<\/a>]. Par ce symbole&#x002C; l\u2019Agence europ\u00e9enne des m\u00e9dicaments (<em>European Medicines Agency<\/em>\u00a0ou EMA) d\u00e9sire inciter les m\u00e9decins et pharmaciens \u00e0 notifier toute suspicion d\u2019effet(s) ind\u00e9sirable(s) avec ces m\u00e9dicaments&#x002C; m\u00eame en cas de doute quant \u00e0 la relation de causalit\u00e9.<\/p>\n<p>La liste des m\u00e9dicaments concern\u00e9s par le symbole\u00a0\u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='font-size:11px; height:10px; width:10px' \/>\u00a0dans le R\u00e9pertoire (version juin 2014)\u00a0peut \u00eatre consult\u00e9e via \u00ab<a href='\/inemedUserfiles\/File\/BT-afmps-13032015.pdf'>Liste des nouveaux m\u00e9dicaments portant le symbole<\/a>\u00a0<img alt='' src='https:\/\/www.bcfi.be\/IMAGES\/SURV.GIF' style='font-size:11px; height:10px; width:10px' \/>\u00bb. \u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Afin d\u2019attirer davantage l\u2019attention sur les sp\u00e9cialit\u00e9s qui font l\u2019objet  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188209","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188209"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188209\/revisions"}],"predecessor-version":[{"id":190764,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188209\/revisions\/190764"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}