{"id":188207,"date":"2015-03-16T00:00:00","date_gmt":"2015-03-15T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/repertoire-commente-des-medicaments-edition-2015-changements-importants-et-comment-se-procurer-un-exemplaire\/"},"modified":"2026-08-27T15:11:24","modified_gmt":"2026-08-27T13:11:24","slug":"repertoire-commente-des-medicaments-edition-2015-changements-importants-et-comment-se-procurer-un-exemplaire","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/repertoire-commente-des-medicaments-edition-2015-changements-importants-et-comment-se-procurer-un-exemplaire\/","title":{"rendered":"REPERTOIRE COMMENTE DES MEDICAMENTS, EDITION 2015. CHANGEMENTS IMPORTANTS ET COMMENT SE PROCURER UN EXEMPLAIRE?"},"content":{"rendered":"<div class='tekst'>\n<p> \u00a0<\/p>\n<p> L\u2019\u00e9dition 2015 du R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments sera bient\u00f4t distribu\u00e9e. Cette version imprim\u00e9e reprend les sp\u00e9cialit\u00e9s commercialis\u00e9es en Belgique au 1<sup>er <\/sup>janvier 2015. Dans la version \u00e9lectronique du R\u00e9pertoire sur notre site Web (<a href='https:\/\/www.cbip.be\/'>www.cbip.be<\/a>&#x002C; update mars 2015)&#x002C; les textes introductifs ont d\u00e9j\u00e0 \u00e9t\u00e9 adapt\u00e9s comme dans la version imprim\u00e9e de 2015; les sp\u00e9cialit\u00e9s mentionn\u00e9es sur le site Web et dans les nouvelles applications pour tablettes et smartphones sont mises \u00e0 jour mensuellement. Une version PDF de l\u2019\u00e9dition 2015 du R\u00e9pertoire est disponible en cliquant <a href='\/inemedUserfiles\/File\/bcfi_fr_GGR_2015_090315_DEF.pdf'>ici<\/a>&#x002C; ainsi que sur <a href='https:\/\/www.cbip.be\/'>www.cbip.be<\/a>> T\u00e9l\u00e9charger > RCM-Archive. Les applications pour tablettes et smartphones peuvent \u00eatre t\u00e9l\u00e9charg\u00e9es gratuitement via <em>App Store<\/em> ou <em>Google Play Store<\/em> (recherche par \u00ab\u00a0cbip\u00a0\u00bb ou \u00ab\u00a0r\u00e9pertoire des m\u00e9dicaments\u00a0\u00bb).<\/p>\n<p> \u00a0&#8211; Comme chaque ann\u00e9e&#x002C; <strong>les textes introductifs de tous les chapitres <\/strong>ont \u00e9t\u00e9 mis \u00e0 jour&#x002C; notamment gr\u00e2ce \u00e0 la collaboration de nombreux experts. Ils donnent un aper\u00e7u de l\u2019\u00e9tat des connaissances actuelles en pharmacoth\u00e9rapie&#x002C; sans en donner tous les d\u00e9tails possibles. Vous retrouverez des explications sur l\u2019objectif et le contenu des rubriques des diff\u00e9rents chapitres dans l\u2019Introduction (voir Intro.2).<\/p>\n<p> &#8211;<strong>Les changements importants dans l\u2019\u00e9dition 2015 sont les suivants:<\/strong><\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La <strong>rubrique <\/strong>\u201c<strong>Contre-indications<\/strong>\u201d a \u00e9t\u00e9 revue syst\u00e9matiquement. Le <em>British National Formulary<\/em> a \u00e9t\u00e9 utilis\u00e9 comme source principale&#x002C; avec des informations compl\u00e9mentaires \u00e9ventuelles provenant du R\u00e9sum\u00e9 des Caract\u00e9ristiques du Produit (RCP) et d\u2019autres sources telles que <em>Farmacotherapeutisch <\/em>Kompas et <em>Martindale<\/em>.<\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La <strong>rubrique \u201cInteractions\u201d <\/strong>a \u00e9t\u00e9 revue syst\u00e9matiquement. Une plus grande attention a \u00e9t\u00e9 accord\u00e9e aux interactions pharmacodynamiques&#x002C; pour lesquelles <em>Stockley\u2019s Drug Interactions<\/em> a \u00e9t\u00e9 utilis\u00e9 comme source principale. Les interactions pharmacocin\u00e9tiques sur base de l\u2019iso-enzyme CYP du cytochrome P450 et de la glycoprot\u00e9ine P (P-gp) ont \u00e9t\u00e9 revues selon une m\u00e9thodologie standardis\u00e9e \u00a0(voir Intro.2. dans le R\u00e9pertoire).<\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les <strong>dispositifs intra-ut\u00e9rins cuivr\u00e9s <\/strong>sont \u00e0 pr\u00e9sent \u00e9galement mentionn\u00e9s dans le R\u00e9pertoire: voir chapitre 6.2.3.<\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Un nouveau sous-chapitre\u00a0 \u201c<strong>10.14. M\u00e9dicaments utilis\u00e9s dans la scl\u00e9rose en plaques\u201d<\/strong> a \u00e9t\u00e9 ajout\u00e9.<\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Le chapitre 15.10. <\/strong><strong>Pansements actifs <\/strong>a \u00e9t\u00e9 retravaill\u00e9&#x002C; avec l\u2019introduction de l\u2019instrument d\u2019observation de la plaie \u201cTIME\u201d (T=<em>Tissue viability<\/em>; I=<em>Infection<\/em>; M=<em>Moisture imbalance; <\/em>E=<em>Edge of the wound<\/em>). Le TIME permet l\u2019\u00e9valuation de la plaie et aide \u00e0 d\u00e9terminer quelle sera la prise en charge. Ceci s\u2019est fait gr\u00e2ce \u00e0 l\u2019avis des experts du <em>EduWond UZGent<\/em> (<a href='https:\/\/www.augent.be\/eduwond'>www.augent.be\/eduwond<\/a>).<\/p>\n<p> \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dans le chapitre \u201c<strong>18.2. <\/strong><strong>Anesth\u00e9sie locale<\/strong>\u201d figurent dor\u00e9navant \u00e9galement les <strong>anesth\u00e9siques locaux pour usage en dentisterie<\/strong>&#x002C; \u00e0 la demande de plusieurs dentistes: il s\u2019agit aussi bien des pr\u00e9parations pour application au niveau des muqueuses que des pr\u00e9parations injectables.<\/p>\n<p> \u00a0<\/p>\n<p> <strong>Comment se procurer un exemplaire de l\u2019\u00e9dition 2015 du R\u00e9pertoire?<\/strong><\/p>\n<p style='margin-left:18.0pt;'> &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les personnes qui re\u00e7oivent r\u00e9guli\u00e8rement les publications du CBIP recevront automatiquement un exemplaire du R\u00e9pertoire dans le courant du mois de mai.<\/p>\n<p style='margin-left:18.0pt;'> &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les personnes qui sont actives dans le secteur des soins de sant\u00e9 et qui ne re\u00e7oivent pas nos publications peuvent demander un exemplaire du R\u00e9pertoire \u00e0 l\u2019adresse e-mail\u00a0<a href='mailto:administration@cbip.be'>administration@cbip.be<\/a><\/p>\n<p style='margin-left:18.0pt;'> &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les universit\u00e9s&#x002C; les Hautes \u00c9coles&#x002C; certaines \u00e9coles de l\u2019enseignement secondaire&#x002C; les h\u00f4pitaux et les maisons de repos et de soins ayant manifest\u00e9 leur int\u00e9r\u00eat pour le R\u00e9pertoire les ann\u00e9es pr\u00e9c\u00e9dentes&#x002C; ont re\u00e7u un courrier leur demandant de pr\u00e9ciser les quantit\u00e9s souhait\u00e9es. Pour les \u00e9tudiants et stagiaires\u00a0en m\u00e9decine&#x002C; pharmacie&#x002C; dentisterie&#x002C; nursing et obst\u00e9trique&#x002C;\u00a0la r\u00e9partition se fait par le d\u00e9partement responsable de leur facult\u00e9 ou de leur \u00e9cole\u00a0(les exemplaires\u00a0ne sont pas\u00a0envoy\u00e9s directement aux \u00e9tudiants ou stagiaires).<\/p>\n<p style='margin-left:18.0pt;'> &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u2019autres organismes actifs dans le secteur des soins de sant\u00e9 d\u00e9sirant recevoir des R\u00e9pertoires&#x002C; peuvent\u00a0 en faire la demande \u00e0 l\u2019adresse e-mail <a href='mailto:administration@cbip.be'>administration@cbip.be<\/a><\/p>\n<p style='margin-left:18.0pt;'> &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Quatre exemplaires maximum seront exp\u00e9di\u00e9s par la poste; les commandes de\u00a0plus de 4 exemplaires doivent \u00eatre retir\u00e9es sur rendez-vous\u00a0(via l\u2019adresse e-mail administration@cbip.be) \u00e0 l\u2019adresse suivante: CBIP&#x002C; c\/o Agence F\u00e9d\u00e9rale des M\u00e9dicaments et des Produits de Sant\u00e9 (AFMPS)&#x002C; Eurostation&#x002C; bloc II&#x002C; 8e \u00e9tage&#x002C; Place Victor Horta 40&#x002C; bte 40&#x002C; 1060 Bruxelles.<\/p>\n<p> \u00a0<\/p>\n<p> <strong>Note concernant l\u2019envoi par la poste des Folia et du R\u00e9pertoire aux m\u00e9decins&#x002C; pharmaciens et dentistes&#x002C; et concernant les changements d\u2019adresse<\/strong><\/p>\n<p> <font face='Arial&#x002C; sans-serif'><span style='font-size: 11px; line-height: 12.6499996185303px;'>Pour l&rsquo;envoi des Folia Pharmacotherapeutica et du R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments&#x002C; nous reprenons l&rsquo;adresse postale des m\u00e9decins&#x002C; pharmaciens et dentistes \u00e0 partir de la base de donn\u00e9es de la Banque-Carrefour de la S\u00e9curit\u00e9 Sociale; c<\/span><\/font>ela signifie que ces publications sont uniquement envoy\u00e9es \u00e0 l\u2019adresse priv\u00e9e. Les m\u00e9decins&#x002C; pharmaciens et dentistes ne doivent pas communiquer des changements d\u2019adresse postale au CBIP; ces changements nous sont transmis par la Banque-Carrefour. Il peut y avoir un retard de 2 \u00e0 3 mois avant que les publications ne soient envoy\u00e9es \u00e0 la nouvelle adresse postale.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 L\u2019\u00e9dition 2015 du R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments sera bient\u00f4t  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188207","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188207"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188207\/revisions"}],"predecessor-version":[{"id":190762,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188207\/revisions\/190762"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}