{"id":188191,"date":"2015-05-08T00:00:00","date_gmt":"2015-05-07T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/extrapolations-vers-la-pratique-clinique-de-modeles-biologiques-et-de-resultats-portant-sur-des-criteres-devaluation-intermediaires-une-approche-critique-reste-indispensable-discussion-sur\/"},"modified":"2026-08-27T15:11:24","modified_gmt":"2026-08-27T13:11:24","slug":"extrapolations-vers-la-pratique-clinique-de-modeles-biologiques-et-de-resultats-portant-sur-des-criteres-devaluation-intermediaires-une-approche-critique-reste-indispensable-discussion-sur","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/extrapolations-vers-la-pratique-clinique-de-modeles-biologiques-et-de-resultats-portant-sur-des-criteres-devaluation-intermediaires-une-approche-critique-reste-indispensable-discussion-sur\/","title":{"rendered":"Extrapolations vers la pratique clinique de mod\u00e8les biologiques et de r\u00e9sultats portant sur des crit\u00e8res d\u2019\u00e9valuation interm\u00e9diaires: une approche critique reste indispensable. Discussion sur base de deux publications r\u00e9centes."},"content":{"rendered":"<div class='tekst'>\n<p class='western' lang='nl-BE' style='margin-bottom: 0.35cm; line-height: 200%'> \u00a0<\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0.35cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Deux publications parues r\u00e9cemment sous des titres \u00e9vocateurs pourraient mener \u00e0 des conclusions erron\u00e9es en cas de lecture trop rapide. La premi\u00e8re publication concerne un \u00e9ditorial dans <\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'><i>The BMJ<\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> intitul\u00e9 \u201c<\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'><i>Serotonin and depression. The marketing of a myth.<\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>\u201d.<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote1sym' name='sdfootnote1anc'><sup>1<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> La deuxi\u00e8me publication concerne un article paru dans une lettre d\u2019information \u00e9lectronique ayant pour titre \u201cCholest\u00e9rol \u00e9lev\u00e9 \u00e9galement d\u00e9favorable pour les personnes \u00e2g\u00e9es\u201d.<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote2sym' name='sdfootnote2anc'><sup>2<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> <\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0.35cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>La r\u00e9daction du CBIP estime qu\u2019il est n\u00e9cessaire de faire un commentaire au sujet de ces publications. D\u2019une part&#x002C; elles illustrent que le titre d\u2019un article ne refl\u00e8te pas toujours son contenu et qu\u2019une lecture critique de tout l\u2019article est importante. D\u2019autre part&#x002C; elles illustrent le fait que des mod\u00e8les biologiques (p.ex. s\u00e9rotonine et d\u00e9pression) ou des r\u00e9sultats d\u2019\u00e9tudes avec des crit\u00e8res d\u2019\u00e9valuation interm\u00e9diaires (p.ex. r\u00e9duction des taux de cholest\u00e9rol LDL) ne permet pas de r\u00e9pondre \u00e0 la question de savoir si un m\u00e9dicament a une valeur th\u00e9rapeutique cliniquement significative. De telles donn\u00e9es peuvent seulement servir de base pour formuler une hypoth\u00e8se et elles ne se substituent pas aux preuves provenant d\u2019\u00e9tudes cliniques avec des crit\u00e8res d\u2019\u00e9valuation forts (p.ex. morbidit\u00e9 et mortalit\u00e9)<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote3sym' name='sdfootnote3anc'><sup>3<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>.<\/span><\/font><\/font><\/p>\n<p class='western' style='margin-bottom: 0.35cm; line-height: 200%'> \u00a0<\/p>\n<ol>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0.35cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='en-US'><b>L\u2019\u00e9ditorial \u201c<\/b><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='en-CA'><i><b>Serotonin and depression. The marketing of a myth.\u201d<\/b><\/i><\/span><\/font><\/font><\/p>\n<\/li>\n<\/ol>\n<p lang='nl-BE' style='margin-bottom: 0.35cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>&#8211; Cet \u00e9ditorial paru dans <\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'><i>The BMJ<\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> a \u00e9t\u00e9 \u00e9crit par David Healy&#x002C; un psychiatre renomm\u00e9 parfois controvers\u00e9 dans le domaine de la psychopharmacoth\u00e9rapie. Il parle d\u2019un \u201cmythe li\u00e9 \u00e0 la s\u00e9rotonine\u201d&#x002C; une hypoth\u00e8se r\u00e9pandue sugg\u00e9rant que la d\u00e9pression est due \u00e0 un d\u00e9s\u00e9quilibre de la s\u00e9rotonine dans le cerveau et que les antid\u00e9presseurs du groupe des ISRS visant \u00e0 \u201cnormaliser\u201d ce d\u00e9s\u00e9quilibre sont une solution toute faite pour le traitement de la d\u00e9pression. D\u2019apr\u00e8s David Healy&#x002C; ceci est simpliste et incorrect&#x002C; mais a \u00e9t\u00e9 admis \u00e0 tort par un grand nombre de professionnels de la sant\u00e9 et de patients&#x002C; au moyen de strat\u00e9gies marketing bien pens\u00e9es. Selon Healy&#x002C; cette hypoth\u00e8se est \u00e9galement \u00e0 l\u2019origine de la surm\u00e9dicalisation des affections psychiatriques telles que la d\u00e9pression et de la surconsommation d\u2019ISRS.<\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'>&#8211; <\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><b>Commentaire de la r\u00e9daction<\/b><\/font><\/font><\/p>\n<ul>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>La consommation excessive de psychotropes tels que les antid\u00e9presseurs est en effet probl\u00e9matique&#x002C; \u00e9galement en Belgique.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Healy a en effet raison qu\u2019il est simpliste d\u2019affirmer qu\u2019un d\u00e9s\u00e9quilibre de la s\u00e9rotonine est la seule cause de la d\u00e9pression. Bien que certains sympt\u00f4mes survenant lors d\u2019une d\u00e9pression pourraient peut-\u00eatre s\u2019expliquer (en partie) par des modifications des concentrations de neurotransmetteurs centraux tels que la s\u00e9rotonine&#x002C; ceci ne prouve pas encore que ces modifications soient la cause de la d\u00e9pression. On estime que les causes de la d\u00e9pression sont multifactorielles et qu\u2019elles impliquent aussi bien des m\u00e9chanismes biologiques &#8211; que des m\u00e9canismes psychosociaux.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Cela signifie-t-il alors que l\u2019on doive abandonner l\u2019emploi des ISRS &#8211; comme on pourrait le conclure sur base de l\u2019\u00e9ditorial de Healy -? Ce serait une conclusion trop simpliste et erron\u00e9e. D\u2019une part&#x002C; il est clair que l\u2019efficacit\u00e9 des antid\u00e9presseurs (ISRS&#x002C; mais \u00e9galement les antid\u00e9presseurs tricycliques et autres) n\u2019est pas prouv\u00e9e en cas de d\u00e9pression mineure (infraliminaire)&#x002C; et que leur rapport b\u00e9n\u00e9fice\/risque n\u2019est pas favorable dans les formes l\u00e9g\u00e8res de d\u00e9pression majeure. D\u2019autre part&#x002C; les antid\u00e9presseurs peuvent avoir une place dans les formes s\u00e9v\u00e8res de d\u00e9pression majeure&#x002C; mais m\u00eame chez ces patients&#x002C; la valeur r\u00e9elle des antid\u00e9presseurs est difficile \u00e0 \u00e9valuer (entre autres en raison de la faible qualit\u00e9 des \u00e9tudes&#x002C; des biais de publications tr\u00e8s marqu\u00e9s \u2013 voir \u00e0 ce sujet les Folia de septembre 2012 \u2013 et de l\u2019effet placebo important). Les donn\u00e9es n\u2019indiquent pas de diff\u00e9rences d\u2019efficacit\u00e9 importantes entre les ISRS et les autres classes d\u2019antid\u00e9presseurs. Lors du choix d\u2019un antid\u00e9presseur&#x002C; le risque d\u2019effets ind\u00e9sirables entre autres a \u00e9galement un r\u00f4le important; il est admis que la toxicit\u00e9 en cas de surdosage est beaucoup plus faible avec les ISRS qu\u2019avec les antid\u00e9presseurs tricycliques.<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote4sym' name='sdfootnote4anc'><sup>4<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> [Voir aussi R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments (<\/span><\/font><\/font><font color='#0000ff'><u><a class='western' href='https:\/\/www.cbip.be\/GGR\/Index.cfm?ggrWelk=\/GGR\/MPG\/MPG_JC.cfm'><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>chapitre 10.3<\/span><\/font><\/font><\/a><\/u><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>) et <\/span><\/font><\/font><font color='#0000ff'><u><a class='western' href='https:\/\/www.cbip.be\/Folia\/2006\/F33F03B.cfm'><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Folia de mars 2006<\/span><\/font><\/font><\/a><\/u><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> et <\/span><\/font><\/font><font color='#0000ff'><u><a class='western' href='https:\/\/www.cbip.be\/Folia\/2008\/F35F05E.cfm'><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>mai 2008<\/span><\/font><\/font><\/a><\/u><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>.]<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Un rapport du KCE publi\u00e9 en 2014 recommande&#x002C; sur base de la litt\u00e9rature&#x002C; une psychoth\u00e9rapie en cas de d\u00e9pression majeure chez l\u2019adulte&#x002C; de pr\u00e9f\u00e9rence en association \u00e0 un traitement m\u00e9dicamenteux mais \u00e9ventuellement en monoth\u00e9rapie; ce rapport sera discut\u00e9 dans un des prochains num\u00e9ros des Folia.<\/span><\/font><\/font><\/p>\n<\/li>\n<\/ul>\n<p style='margin-left: 1.91cm; margin-bottom: 0cm; line-height: 200%'> \u00a0<\/p>\n<ol start='2'>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'><b>L\u2019article \u201cCholest\u00e9rol \u00e9lev\u00e9 \u00e9galement d\u00e9favorable chez les personnes \u00e2g\u00e9es.\u201d<\/b><\/span><\/font><\/font><\/p>\n<\/li>\n<\/ol>\n<p align='justify' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>&#8211; Cet article paru dans une lettre d\u2019information \u00e9lectronique portait sur une \u00e9tude r\u00e9cente men\u00e9e selon le principe de la \u201crandomisation mend\u00e9lienne\u201d (voir plus loin). Il a \u00e9t\u00e9 \u00e9valu\u00e9 s\u2019il existe un lien entre un score de risque g\u00e9n\u00e9tique (d\u00e9termin\u00e9 sur base de certaines variantes au niveau de l\u2019ADN)&#x002C; le taux de cholest\u00e9rol LDL et l\u2019\u00e2ge avanc\u00e9. Il ressort de l\u2019\u00e9tude que les personnes ayant un faible score de risque g\u00e9n\u00e9tique pr\u00e9sentaient aussi des taux de cholest\u00e9rol LDL moins \u00e9lev\u00e9s et avaient \u00e9galement plus de chance d\u2019atteindre un \u00e2ge avanc\u00e9<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote5sym' name='sdfootnote5anc'><sup>5<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>. Ces r\u00e9sultats semblent donc en contradiction avec des \u00e9tudes observationnelles ant\u00e9rieures dans lesquelles un taux de cholest\u00e9rol LDL \u00e9lev\u00e9 semblait associ\u00e9 \u00e0 une plus faible mortalit\u00e9 chez les personnes tr\u00e8s \u00e2g\u00e9es&#x002C; contrairement \u00e0 ce qui \u00e9tait observ\u00e9 chez des personnes plus jeunes. <\/span><\/font><\/font><\/p>\n<p align='justify' class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'>&#8211; <\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><b>Commentaire de la r\u00e9daction<\/b><\/font><\/font><\/p>\n<ul>\n<li>\n<p align='justify' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Contrairement \u00e0 ce que semble indiquer son nom&#x002C; aucune randomisation n\u2019est effectu\u00e9e lors d\u2019une \u201crandomisation mend\u00e9lienne\u201d. Il s\u2019agit d\u2019une forme d\u2019\u00e9tudes observationnelles. Pour le lecteur int\u00e9ress\u00e9 par les aspects m\u00e9thodologiques&#x002C; nous renvoyons \u00e0 un article clair et libre d\u2019acc\u00e8s \u00e0 ce sujet<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote6sym' name='sdfootnote6anc'><sup>6<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p align='justify' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Cette \u00e9tude permet uniquement de pr\u00e9sumer un lien entre un faible taux de cholest\u00e9rol LDL et une esp\u00e9rance de vie \u00e9lev\u00e9e. On ne peut pas en d\u00e9duire qu\u2019un traitement hypolipid\u00e9miant puisse prolonger la vie des personnes tr\u00e8s \u00e2g\u00e9es.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p align='justify' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Doit-on prescrire des statines aux personnes tr\u00e8s \u00e2g\u00e9es en bonne sant\u00e9 ayant un taux de cholest\u00e9rol LDL \u00e9lev\u00e9&#x002C; comme le sugg\u00e8re la lettre d\u2019information \u00e9lectronique ? On dispose de tr\u00e8s peu d\u2019 \u00e9tudes randomis\u00e9es sur les statines chez les personnes tr\u00e8s \u00e2g\u00e9es. Dans l\u2019\u00e9tude PROSPER<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote7sym' name='sdfootnote7anc'><sup>7<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'> ayant inclus des personnes \u00e2g\u00e9es de 70 \u00e0 82 ans&#x002C; un effet favorable a \u00e9t\u00e9 observ\u00e9 avec la pravastatine sur le nombre d\u2019\u00e9v\u00e8nements cardio-vasculaires&#x002C; mais pas en ce qui concerne la mortalit\u00e9 totale. On ne dispose pas d\u2019\u00e9tudes randomis\u00e9es chez des personnes \u00e2g\u00e9es de plus de 82 ans. De plus&#x002C; les personnes tr\u00e8s \u00e2g\u00e9es&#x002C; vuln\u00e9rables et souvent polym\u00e9diqu\u00e9es&#x002C; pr\u00e9sentent souvent un risque \u00e9lev\u00e9 d\u2019effets ind\u00e9sirables et d\u2019interactions avec les statines.<\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'><span style='background: #ffff00'> <\/span><\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p align='justify' lang='nl-BE' style='margin-bottom: 0cm; line-height: 200%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-FR'>Pour conclure&#x002C; on peut dire que cette nouvelle \u00e9tude n\u2019ajoute rien aux preuves scientifiques d\u00e9j\u00e0 disponibles et qu\u2019un traitement syst\u00e9matique par une statine chez des personnes tr\u00e8s \u00e2g\u00e9es ne se justifie pas.<\/span><\/font><\/font><\/p>\n<\/li>\n<\/ul>\n<div id='sdfootnote1'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote1anc' name='sdfootnote1sym'>1<\/a> <i>The <\/i><font color='#333333'><i><span style='background: #ffffff'>BMJ<\/span><\/i><\/font><font color='#333333'><span style='background: #ffffff'>\u00a0<\/span><\/font><font color='#555555'><span style='background: #ffffff'>2015<\/span><\/font><font color='#333333'><span style='background: #ffffff'>;<\/span><\/font><font color='#555555'><span style='background: #ffffff'>350:h1771<\/span><\/font><font color='#333333'><span style='background: #ffffff'>\u00a0(<\/span><\/font><font color='#333333'><span style='background: #ffffff'>doi:10.1136\/bmj.h1771); l\u2019\u00e9ditorial est accessible librement via <\/span><\/font><font color='#0000ff'><u><a class='western' href='https:\/\/www.bmj.com\/content\/350\/bmj.h1771'>www.bmj.com\/content\/350\/bmj.h1771<\/a><\/u><\/font><\/p>\n<\/p><\/div>\n<div id='sdfootnote2'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote2anc' name='sdfootnote2sym'>2<\/a> <font color='#0000ff'><u><a class='western' href='https:\/\/www.mediplanet.be\/'>www.mediplanet.be\/<\/a><\/u><\/font>&#x002C; <span lang='fr-FR'>article de <\/span>22\/04\/15 ( avec mot de passe DocCheck)<\/p>\n<\/p><\/div>\n<div id='sdfootnote3'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote3anc' name='sdfootnote3sym'>3<\/a> <i>The BMJ<\/i> 2011;343:d7995 (doi:10.1136\/bmj.d7995) ; Minerva 2014;13:90 (<font color='#0000ff'><u><a class='western' href='https:\/\/www.minerva-ebp.be\/nl\/article\/8\/search\/'>https:\/\/www.minerva-ebp.be\/nl\/article\/8\/search\/<\/a><\/u><\/font>) en 116 (<font color='#0000ff'><u><a class='western' href='https:\/\/www.minerva-ebp.be\/nl\/article\/1290\/search\/'>https:\/\/www.minerva-ebp.be\/nl\/article\/1290\/search\/<\/a><\/u><\/font><\/p>\n<\/p><\/div>\n<div id='sdfootnote4'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote4anc' name='sdfootnote4sym'>4<\/a><span lang='en-US'> <\/span><span lang='en-US'>Martindale (version \u00e9lectronique)\u00a0; NICE:\u201d The treatment and management of depression in adults.\u201d National Clinical Practice Guideline 90 (2010)&#x002C; <\/span><span lang='en-US'><i>Full Guideline<\/i><\/span><span lang='en-US'> (via <\/span><font color='#0000ff'><u><a class='western' href='https:\/\/www.nice.org.uk\/guidance\/cg90\/evidence\/cg90-depression-in-adults-full-guidance2'><span lang='en-US'>https:\/\/www.nice.org.uk\/guidance\/cg90\/evidence\/cg90-depression-in-adults-full-guidance2<\/span><\/a><\/u><\/font><span lang='en-US'> <\/span><\/p>\n<\/p><\/div>\n<div id='sdfootnote5'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote5anc' name='sdfootnote5sym'>5<\/a> <i>Int J Epidemiol<\/i> 2015&#x002C; 1-9 (doi: 10.1093\/ije\/dyv031)<\/p>\n<\/p><\/div>\n<div id='sdfootnote6'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote6anc' name='sdfootnote6sym'>6<\/a><span lang='fr-FR'> <\/span><span lang='fr-FR'><i>BMJ<\/i><\/span><i><span lang='fr-FR'> <\/span><\/i><span lang='fr-FR'>2012<\/span><i><span lang='fr-FR'>; <\/span><\/i><span lang='fr-FR'>345<\/span><i><span lang='fr-FR'> (<\/span><\/i><span lang='fr-FR'>doi: <\/span><font color='#0000ff'><u><a class='western' href='https:\/\/dx.doi.org\/10.1136\/bmj.e7325'><span lang='fr-FR'>https:\/\/dx.doi.org\/10.1136\/bmj.e7325<\/span><\/a><\/u><\/font><span lang='fr-FR'>)<\/span><\/p>\n<\/p><\/div>\n<div id='sdfootnote7'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote7anc' name='sdfootnote7sym'>7<\/a> <span lang='fr-BE'><i>Lancet <\/i><\/span><span lang='fr-BE'>2002\u00a0;360\u00a0:1623-30<\/span><\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Deux publications parues r\u00e9cemment sous des titres \u00e9vocateurs pourraient  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188191","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188191"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188191\/revisions"}],"predecessor-version":[{"id":190746,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188191\/revisions\/190746"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}