{"id":188183,"date":"2015-06-05T00:00:00","date_gmt":"2015-06-04T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/vaccination-des-enfants-contre-la-varicelle-davantage-de-donnees-sont-necessaires-avant-de-recommander-une-vaccination-generalisee\/"},"modified":"2026-08-27T15:11:23","modified_gmt":"2026-08-27T13:11:23","slug":"vaccination-des-enfants-contre-la-varicelle-davantage-de-donnees-sont-necessaires-avant-de-recommander-une-vaccination-generalisee","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/vaccination-des-enfants-contre-la-varicelle-davantage-de-donnees-sont-necessaires-avant-de-recommander-une-vaccination-generalisee\/","title":{"rendered":"Vaccination des enfants contre la varicelle: davantage de donn\u00e9es sont n\u00e9cessaires avant de recommander une vaccination g\u00e9n\u00e9ralis\u00e9e"},"content":{"rendered":"<div class='tekst'>\n<p class='western' lang='fr-BE' style='margin-bottom: 0cm; line-height: 150%'> \u00a0<\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>Un chercheur a r\u00e9cemment plaid\u00e9 dans les m\u00e9dias en faveur d\u2019une vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle. Selon lui&#x002C; l\u2019argument en faveur de la vaccination consiste en la protection contre les complications graves de la varicelle&#x002C; parmi lesquelles un risque potentiel d\u2019accident vasculaire c\u00e9r\u00e9bral (AVC) isch\u00e9mique. Sa recherche a montr\u00e9 qu\u2019un certain nombre d\u2019arguments contre la vaccination g\u00e9n\u00e9ralis\u00e9e seraient moins importants que ce que l\u2019on craignait dans un premier temps; d\u2019o\u00f9 son appel \u00e0 une nouvelle analyse co\u00fbt\/b\u00e9n\u00e9fice. <\/span><\/font><\/font><\/p>\n<p class='western' lang='fr-BE' style='margin-bottom: 0cm; line-height: 150%'> \u00a0<\/p>\n<p class='western' lang='fr-BE' style='margin-bottom: 0cm; line-height: 150%'> \u00a0<\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'><b>Recommandations actuelles concernant la vaccination contre la varicelle en Belgique <\/b><\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>En Belgique&#x002C; la vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle n\u2019est actuellement pas recommand\u00e9e.<\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>-Le Conseil Sup\u00e9rieur de la Sant\u00e9&#x002C; dans son avis de 2005&#x002C; ne recommande la vaccination contre la varicelle que dans les groupes \u00e0 risque tels les professionnels de la sant\u00e9 non immuns et d\u2019autres personnes non immunes fr\u00e9quemment en contact avec des patients immunod\u00e9prim\u00e9s&#x002C; et \u00e9ventuellement chez certains enfants et adultes avec un risque de varicelle s\u00e9v\u00e8re (p.ex. dans l\u2019attente d\u2019une transplantation; leuc\u00e9mie lympho\u00efde aigu\u00eb en r\u00e9mission)<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote1sym' name='sdfootnote1anc'><sup>1<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>.<\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>&#8211; La conclusion d\u2019un rapport du Centre F\u00e9d\u00e9ral des Soins de Sant\u00e9 (KCE) de 2010 (KCE Reports 151A) est qu\u2019une vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle ne peut avoir un bon rapport co\u00fbt-efficacit\u00e9 que si l\u2019on a la certitude que l\u2019incidence du zona chez l\u2019adulte n\u2019augmentera pas de mani\u00e8re trop importante suite \u00e0 la vaccination g\u00e9n\u00e9ralis\u00e9e<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote2sym' name='sdfootnote2anc'><sup>2<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>. <\/span><\/font><\/font><\/p>\n<p class='western' lang='fr-BE' style='margin-bottom: 0cm; line-height: 150%'> \u00a0<\/p>\n<p class='western' lang='fr-BE' style='margin-bottom: 0cm; line-height: 150%'> \u00a0<\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'><b>Commentaire du CBIP<\/b><\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>&#8211; La protection contre les complications graves de la varicelle est un argument en faveur de la vaccination g\u00e9n\u00e9ralis\u00e9e des enfants. Il convient n\u00e9anmoins de signaler que le risque de complications est faible: il s\u2019agit surtout de surinfections des l\u00e9sions cutan\u00e9es; tr\u00e8s rarement d\u2019une ataxie c\u00e9r\u00e9belleuse (estim\u00e9e \u00e0 1\/4.000 patients \u00e2g\u00e9s de moins de 15 ans) et d\u2019une enc\u00e9phalite (estim\u00e9e \u00e0 1\/10.000 \u00e0 1\/100.000 patients \u00e2g\u00e9s de moins de 15 ans)<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote3sym' name='sdfootnote3anc'><sup>3<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>. Les donn\u00e9es concernant le risque d\u2019un AVC isch\u00e9mique sont tr\u00e8s limit\u00e9es: des \u00e9tudes observationnelles montrent un lien entre la varicelle et un AVC isch\u00e9mique&#x002C; la plupart des cas survenant dans les 12 mois apr\u00e8s l\u2019infection avec une incidence estim\u00e9e \u00e0 1\/15.000 enfants atteints de varicelle. <\/span><\/font><\/font><\/p>\n<p class='western' lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>&#8211; Le b\u00e9n\u00e9fice potentiel de la vaccination doit \u00eatre mis en balance avec plusieurs facteurs. <\/span><\/font><\/font><\/p>\n<ul>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>Les effets ind\u00e9sirables et contre-indications des vaccins contre la varicelle (Provarivax\u00ae&#x002C; Varilrix\u00ae; vaccin combin\u00e9: Priorix Tetra\u00ae). Il s\u2019agit de vaccins vivants qui sont de ce fait contre-indiqu\u00e9s chez les patients immunod\u00e9prim\u00e9s par exemple.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>Les incertitudes quant \u00e0 la dur\u00e9e de protection du vaccin. Avec un sch\u00e9ma de vaccination \u00e0 2 doses&#x002C; un effet protecteur a \u00e9t\u00e9 constat\u00e9 jusqu\u2019\u00e0 10 ans apr\u00e8s la vaccination<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote4sym' name='sdfootnote4anc'><sup>4<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>. En raison d\u2019une diminution possible de l\u2019immunit\u00e9 plusieurs ann\u00e9es apr\u00e8s la vaccination&#x002C; il est possible que des personnes vaccin\u00e9es contractent la varicelle \u00e0 un \u00e2ge o\u00f9 l\u2019infection est plus s\u00e9v\u00e8re et le risque de complications plus \u00e9lev\u00e9. En outre&#x002C; les personnes non vaccin\u00e9es auront&#x002C; elles aussi&#x002C; un plus grand risque de contracter la varicelle \u00e0 un \u00e2ge avanc\u00e9&#x002C; notamment parce que le virus circulera moins dans la population plus jeune.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>La possibilit\u00e9 d\u2019une augmentation de l\u2019incidence du zona chez l\u2019adulte suite \u00e0 une vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle (appel\u00e9e hypoth\u00e8se \u201c<\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'><i>boosting <\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>exog\u00e8ne\u201d). Il est en effet admis qu\u2019un contact r\u00e9gulier des adultes avec des enfants atteints de la varicelle entra\u00eene un <\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'><i>boosting <\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>naturel (exog\u00e8ne) de l\u2019immunit\u00e9 contre l\u2019herp\u00e8s zoster. En cas de vaccination g\u00e9n\u00e9ralis\u00e9e&#x002C; il y aura beaucoup moins de virus varicelle-zona circulants&#x002C; et il y aura donc une diminution du <\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'><i>boosting<\/i><\/span><\/font><\/font><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'> naturel etune augmentation possible du risque de zona. Il existe encore beaucoup d\u2019incertitudes en ce qui concerne cette hypoth\u00e8se. Dans les pays o\u00f9 une vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle est d\u00e9j\u00e0 appliqu\u00e9e (entre autres aux Etats unis)&#x002C; les donn\u00e9es sur l\u2019incidence du zona chez l\u2019adulte ne permettent pas de tirer des conclusions<\/span><\/font><\/font><sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><a class='sdfootnoteanc' href='#sdfootnote5sym' name='sdfootnote5anc'><sup>5<\/sup><\/a><\/font><\/font><\/sup><font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>.<\/span><\/font><\/font><\/p>\n<\/li>\n<li>\n<p lang='nl-BE' style='margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>Les cons\u00e9quences pharmaco-\u00e9conomiques (co\u00fbt du vaccin; r\u00e9duction des d\u00e9penses due au nombre plus limit\u00e9 de complications de la varicelle chez les enfants&#x002C; mais d\u00e9penses suppl\u00e9mentaires dues par ex. \u00e0 une augmentation du nombre de cas de zona et \u00e0 l\u2019impact plus important de la maladie chez les adolescents et les adultes) ne sont pas claires. <\/span><\/font><\/font><\/p>\n<\/li>\n<\/ul>\n<p lang='nl-BE' style='margin-left: 0.64cm; margin-bottom: 0cm; line-height: 150%'> <font face='Arial&#x002C; sans-serif'><font size='3' style='font-size: 12pt'><span lang='fr-BE'>&#8211; Dans le R\u00e9pertoire Comment\u00e9 des M\u00e9dicaments&#x002C; le CBIP suit l\u2019avis actuel du Conseil Sup\u00e9rieur de la Sant\u00e9&#x002C; et recommande la vaccination dans certains groupes cibles. Avant de recommander une vaccination g\u00e9n\u00e9ralis\u00e9e des enfants contre la varicelle&#x002C; davantage de donn\u00e9es sont n\u00e9cessaires&#x002C; tant en ce qui concerne le rapport b\u00e9n\u00e9fice\/risque que le rapport co\u00fbt\/b\u00e9n\u00e9fice. <\/span><\/font><\/font><\/p>\n<div id='sdfootnote1'>\n<p style='margin-bottom: 0cm; line-height: 200%'> <span style='font-size:10px;'><a class='sdfootnotesym' href='#sdfootnote1anc' name='sdfootnote1sym'>1<\/a> <\/span><a href='https:\/\/www.health.belgium.be\/internet2Prd\/groups\/public\/@public\/@shc\/documents\/ie2divers\/7428387_fr.pdf'><font face='Arial&#x002C; serif'><font size='2' style='font-size: 10pt'><span lang='fr-BE'>https:\/\/www.health.belgium.be\/internet2Prd\/groups\/public\/@public\/@shc\/documents\/ie2divers\/7428387_fr.pdf<\/span><\/font><\/font><\/a><\/p>\n<\/p><\/div>\n<div id='sdfootnote2'>\n<p style='margin-bottom: 0cm; line-height: 200%'> <span style='font-size:10px;'><a class='sdfootnotesym' href='#sdfootnote2anc' name='sdfootnote2sym'>2<\/a><span lang='en-US'> <\/span><\/span><a href='https:\/\/kce.fgov.be\/fr\/publication\/report\/rapport-co%C3%BBt-utilit%C3%A9-de-la-vaccination-contre-la-varicelle-chez-les-enfants-et-de#.VXF1K8_tmko'><font face='Arial&#x002C; serif'><font size='2' style='font-size: 10pt'><span lang='fr-BE'>https:\/\/kce.fgov.be\/fr\/publication\/report\/rapport-co%C3%BBt-utilit%C3%A9-de-la-vaccination-contre-la-varicelle-chez-les-enfants-et-de#.VXF1K8_tmko<\/span><\/font><\/font><\/a><\/p>\n<p class='sdfootnote-western' lang='fr-FR'> <span lang='en-US'>; <\/span><span lang='en-US'><i>Human Vaccines &#038; Immunotherapeutics<\/i><\/span><span lang='en-US'> 2013;9:812-22 (doi: 10.4161\/hv.23334)<\/span><\/p>\n<\/p><\/div>\n<div id='sdfootnote3'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote3anc' name='sdfootnote3sym'>3<\/a> Varicella zoster-infecties: waterpokken en gordelroos (chapitre 26). Dans : Handboek Vaccinaties. D<font color='#000000'><font face='Verdana&#x002C; sans-serif'><font size='1' style='font-size: 8pt'><span style='letter-spacing: 0.8pt'><i><span style='background: #ffffff'>eel B&#x002C; Infectieziekten en vaccinaties<\/span><\/i><\/span><\/font><\/font><\/font><font color='#000000'><font face='Verdana&#x002C; sans-serif'><font size='1' style='font-size: 8pt'><span style='letter-spacing: 0.8pt'><span style='background: #ffffff'> (<\/span><\/span><\/font><\/font><\/font><font color='#000000'><font face='Verdana&#x002C; sans-serif'><font size='1' style='font-size: 8pt'><span style='letter-spacing: 0.8pt'><span style='background: #ffffff'>Van Gorcum); 2i\u00e8me \u00e9dition (2013)<\/span><\/span><\/font><\/font><\/font><\/p>\n<p class='sdfootnote-western' lang='fr-FR'> \u00a0<\/p>\n<\/p><\/div>\n<div id='sdfootnote4'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote4anc' name='sdfootnote4sym'>4<\/a> <font color='#0000ff'><u><a class='western' href='https:\/\/www.cdc.gov\/vaccines\/vpd-vac\/varicella\/hcp-effective-duration.htm'>www.cdc.gov\/vaccines\/vpd-vac\/varicella\/hcp-effective-duration.htm<\/a><\/u><\/font><\/p>\n<\/p><\/div>\n<div id='sdfootnote5'>\n<p class='sdfootnote-western' lang='fr-FR'> <a class='sdfootnotesym' href='#sdfootnote5anc' name='sdfootnote5sym'>5<\/a> Varicella zoster-infecties: waterpokken en gordelroos (chapitre 26). Dans : Handboek Vaccinaties. D<font color='#000000'><font face='Verdana&#x002C; sans-serif'><font size='1' style='font-size: 8pt'><span style='letter-spacing: 0.8pt'><i><span style='background: #ffffff'>eel B&#x002C; Infectieziekten en vaccinaties<\/span><\/i><\/span><\/font><\/font><\/font><font color='#000000'><font face='Verdana&#x002C; sans-serif'><font size='1' style='font-size: 8pt'><span style='letter-spacing: 0.8pt'><span style='background: #ffffff'> (Van Gorcum); 2i\u00e8me \u00e9dition (2013);<\/span><\/span><\/font><\/font><\/font><\/p>\n<p class='sdfootnote-western' lang='fr-FR'> <font color='#333333'><span style='background: #ffffff'>PLoS ONE 8:e66485 (doi:10.1371\/journal.pone.0066485)<\/span><\/font><\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Un chercheur a r\u00e9cemment plaid\u00e9 dans les m\u00e9dias en  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188183","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188183"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188183\/revisions"}],"predecessor-version":[{"id":190738,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188183\/revisions\/190738"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}