{"id":188135,"date":"2015-09-11T00:00:00","date_gmt":"2015-09-10T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/informations-recentes-septembre-2015-fumarate-de-dimethyle-vedolizumab-ivermectine-propranolol-a-80-mg-a-liberation-prolongee-umeclidinium-canagliflozine-metformine-contraceptif-ora\/"},"modified":"2026-08-27T15:11:21","modified_gmt":"2026-08-27T13:11:21","slug":"informations-recentes-septembre-2015-fumarate-de-dimethyle-vedolizumab-ivermectine-propranolol-a-80-mg-a-liberation-prolongee-umeclidinium-canagliflozine-metformine-contraceptif-ora","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/informations-recentes-septembre-2015-fumarate-de-dimethyle-vedolizumab-ivermectine-propranolol-a-80-mg-a-liberation-prolongee-umeclidinium-canagliflozine-metformine-contraceptif-ora\/","title":{"rendered":"Informations r\u00e9centes septembre 2015: fumarate de dim\u00e9thyle, v\u00e9dolizumab, ivermectine,\u00a0propranolol \u00e0 80 mg \u00e0 lib\u00e9ration prolong\u00e9e,\u00a0um\u00e9clidinium, canagliflozine + metformine, contraceptif oral \u00ab\u00a0\u00e0 cycle \u00e9tendu\u00a0\u00bb, Humalog\u00ae 200 U\/ml, pr\u00e9gabaline, vaccins mis \u00e0 disposition par les Communaut\u00e9s"},"content":{"rendered":"<div class='tekst'>\n<table cellpadding='7' cellspacing='0' style='width:633px'>\n<tbody>\n<tr>\n<td>\n<p><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>: m\u00e9dicament soumis \u00e0 une surveillance particuli\u00e8re et pour lequel la notification d\u2019effets ind\u00e9sirables au Centre Belge de Pharmacovigilance est encourag\u00e9e.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li>\n<p>Le <strong>fumarate de<\/strong> <strong>dim\u00e9thyle <\/strong>(<strong>Tecfidera<\/strong>\u00ae; chapitre 12.3.2.17.) est un immunomodulateur propos\u00e9 en monoth\u00e9rapie par voie orale dans le traitement de la scl\u00e9rose en plaques (SEP) avec alternance de pouss\u00e9es et de r\u00e9missions (<em>Relapsing-Remetting MS<\/em>). Les r\u00e9sultats de deux \u00e9tudes randomis\u00e9es contr\u00f4l\u00e9es par placebo indiquent une diminution statistiquement significative du taux annuel de pouss\u00e9es chez les patients trait\u00e9s par le fumarate de dim\u00e9thyle&#x002C; mais le b\u00e9n\u00e9fice en valeur absolue est faible (< 0&#x002C;2 pouss\u00e9e\/an). Un effet sur l\u2019aggravation de l\u2019invalidit\u00e9 \u00e0 long terme n\u2019est pas d\u00e9montr\u00e9. Les principaux effets ind\u00e9sirables du fumarate de dim\u00e9thyle consistent en des bouff\u00e9es de chaleur&#x002C; des troubles gastro-intestinaux&#x002C; des troubles cutan\u00e9s&#x002C; une lymphop\u00e9nie avec un risque accru d\u2019infections&#x002C; des troubles r\u00e9naux et une augmentation des transaminases h\u00e9patiques. On ne dispose pas d\u2019\u00e9tudes comparatives avec d\u2019autres traitements de la scl\u00e9rose en plaques&#x002C; tel l\u2019interf\u00e9ron b\u00eata&#x002C; et il n\u2019est pas prouv\u00e9 que le fumarate de dim\u00e9thyle apporte une plus-value en termes d\u2019efficacit\u00e9 ou d\u2019innocuit\u00e9. La place du fumarate de dim\u00e9thyle dans la scl\u00e9rose en plaques n\u2019est donc pas encore claire.<a class='sdfootnoteanc' href='#sdfootnote1sym' name='sdfootnote1anc'><sup>1<\/sup><\/a><\/p>\n<\/li>\n<li>\n<p>Le <strong>v\u00e9dolizumab<\/strong> (<strong>Entyvio<\/strong>\u00ae<img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>; chapitre 12.3.2.18.) est un anticorps monoclonal immunosuppresseur proche du natalizumab (Tysabri\u00ae&#x002C; utilis\u00e9 dans la SEP). Le v\u00e9dolizumab est propos\u00e9 dans le traitement des formes actives mod\u00e9r\u00e9es \u00e0 s\u00e9v\u00e8res de la maladie de Crohn et de la colite ulc\u00e9reuse en cas d\u2019\u00e9chec ou d\u2019intol\u00e9rance aux autres traitements (voir chapitre 3.7.). Les r\u00e9sultats de trois RCT ont montr\u00e9 un taux de r\u00e9mission plus \u00e9lev\u00e9 avec le v\u00e9dolizumab par rapport au placebo&#x002C; mais un effet sur le risque de complications ou la n\u00e9cessit\u00e9 d\u2019une intervention chirurgicale n\u2019a pas \u00e9t\u00e9 d\u00e9montr\u00e9&#x002C; et on ne dispose pas d\u2019\u00e9tudes comparatives avec d\u2019autres traitements. Les effets ind\u00e9sirables du v\u00e9dolizumab consistent essentiellement en des r\u00e9actions li\u00e9es \u00e0 la perfusion&#x002C; une sensibilit\u00e9 accrue aux infections et une toxicit\u00e9 h\u00e9patique. Le risque de leucoenc\u00e9phalopathie multifocale progressive observ\u00e9 avec le natalizumab incite \u00e0 la prudence. Il n\u2019est pas prouv\u00e9 que le v\u00e9dolizumab apporte une plus-value par rapport aux inhibiteurs du TNF dans les formes graves de la maladie de Crohn et de la colite ulc\u00e9reuse.<a class='sdfootnoteanc' href='#sdfootnote2sym' name='sdfootnote2anc'><sup>2<\/sup><\/a><\/p>\n<\/li>\n<li>\n<p>L\u2019<strong>ivermectine <\/strong>(<strong>Soolantra<\/strong>\u00ae; chapitre 15.12.) est un antiparasitaire qui pr\u00e9sente \u00e9galement des propri\u00e9t\u00e9s anti-inflammatoires. L\u2019ivermectine est utilis\u00e9e <em>par voie orale<\/em> dans le traitement de la gale [voir Folia d\u2019avril 2015]\u00a0; les comprim\u00e9s d\u2019ivermectine ne sont pas disponibles en Belgique. L\u2019ivermectine sous forme de <em>cr\u00e8me<\/em> \u00e0 1% pr\u00e9sent\u00e9e ici&#x002C; est utilis\u00e9e&#x002C; \u00e0 raison d\u2019une application par jour&#x002C; dans le traitement des l\u00e9sions inflammatoires de la rosac\u00e9e. Ses effets ind\u00e9sirables consistent en irritation cutan\u00e9e&#x002C; prurit&#x002C; sensation de br\u00fblure&#x002C; s\u00e9cheresse cutan\u00e9e. Il n\u2019est pas prouv\u00e9 que l\u2019ivermectine apporte une plus-value par rapport au m\u00e9tronidazole \u00e0 usage local dans le traitement de la rosac\u00e9e.<sup> <sup><a class='sdfootnoteanc' href='#sdfootnote3sym' name='sdfootnote3anc'>3<\/a><\/sup><\/sup><\/p>\n<\/li>\n<li>\n<p><a class='sdfootnoteanc' href='#sdfootnote3sym' name='sdfootnote3anc'>Les comprim\u00e9s de propranolol \u00e0 80 mg \u00e0 lib\u00e9ration prolong\u00e9e (chapitre 1.5.)&#x002C; qui avaient \u00e9t\u00e9 retir\u00e9s du march\u00e9 en juin 2014 [<\/a><a href='https:\/\/www.cbip.be\/Folia\/Index.cfm?FoliaWelk=F41F07E'>voir Folia de juillet 2014<\/a>]&#x002C; sont \u00e0 nouveau disponibles sous le nom de sp\u00e9cialit\u00e9 Propranolol Teva\u00ae.<\/p>\n<\/li>\n<li>\n<p>L\u2019<strong>um\u00e9clidinium<\/strong> (<strong>Incruse<\/strong>\u00ae<img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>; chapitre 4.1.2.2.) est un anticholinergique \u00e0 longue dur\u00e9e d\u2019action (<em>long-acting muscarinic antagonist<\/em> ou <em>LAMA<\/em>) utilis\u00e9 en inhalation dans le traitement d\u2019entretien de la BPCO. L\u2019um\u00e9clidinium \u00e9tait d\u00e9j\u00e0 disponible en association avec le vilant\u00e9rol&#x002C; un \u03b2<sub>2<\/sub>-mim\u00e9tique \u00e0 longue dur\u00e9e d\u2019action&#x002C; sous le nom de sp\u00e9cialit\u00e9 Anoro\u00ae [voir Folia de mars 2015]. L\u2019um\u00e9clidinium expose aux m\u00eames effets ind\u00e9sirables que ceux des autres anticholinergiques inhal\u00e9s (tels que s\u00e9cheresse de la bouche&#x002C; candidose orale&#x002C; palpitations&#x002C; constipation&#x002C; r\u00e9tention urinaire)&#x002C; et il n\u2019est pas prouv\u00e9 que l\u2019um\u00e9clidinium apporte une plus-value par rapport \u00e0 ceux-ci.<a class='sdfootnoteanc' href='#sdfootnote4sym' name='sdfootnote4anc'><sup>4<\/sup><\/a><\/p>\n<\/li>\n<li>\n<p><strong>Vokanamet<\/strong>\u00ae<img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>(chapitre 5.1.10.) est une association fixe de <strong>canagliflozine<\/strong> (une gliflozine&#x002C; chapitre 5.1.9.) et de <strong>metformine<\/strong> (chapitre 5.1.2.). Les gliflozines (syn. inhibiteurs du SGLT2) exercent leur effet hypoglyc\u00e9miant en diminuant l\u2019absorption r\u00e9nale de glucose provoquant ainsi une glucosurie. La posologie est de 100 \u00e0 300 mg (canagliflozine) en deux prises. Les effets ind\u00e9sirables sont ceux des constituants&#x002C; et la prudence s\u2019impose particuli\u00e8rement chez les patients avec une diminution de la fonction r\u00e9nale vu le risque de troubles r\u00e9naux et d\u2019acidoc\u00e9tose [voir aussi \u00ab\u00a0Risque d\u2019acidoc\u00e9tose diab\u00e9tique avec les gliflozines\u00a0\u00bb dans les Folia de septembre 2015]. Le b\u00e9n\u00e9fice d\u2019une telle association fixe en termes d\u2019observance doit \u00eatre mis en balance avec les possibilit\u00e9s plus limit\u00e9es d\u2019adaptation de la dose.<\/p>\n<\/li>\n<li>\n<p><strong>Seasonique<\/strong>\u00ae<img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>\u00a0(chapitre 6.2.1.1.) est un <strong>contraceptif<\/strong> <strong>oral<\/strong> \u00ab\u00a0<strong>\u00e0 cycle \u00e9tendu\u00a0\u00bb<\/strong>&#x002C; \u00e0 prendre en continu pendant trois mois. La posologie de Seasonique\u00ae est la suivante\u00a0: 1 comprim\u00e9 \u00e0 base de 0&#x002C;15 mg de l\u00e9vonorgestrel et de 0&#x002C;03 mg d\u2019\u00e9thinylestradiol pendant 84 jours suivi de 1 comprim\u00e9 \u00e0 base de 0&#x002C;01 mg d\u2019\u00e9thinylestradiol pendant 7 jours au cours desquels surviennent les menstruations; puis le traitement est poursuivi sans interruption. La pilule \u00e0 cycle \u00e9tendu diminue la fr\u00e9quence des menstruations par rapport \u00e0 une pilule monophasique classique&#x002C; mais elle est associ\u00e9e \u00e0 un risque accru de spotting. Il n\u2019est pas prouv\u00e9 que la pilule \u00e0 cycle \u00e9tendu soit plus efficace ou apporte une plus-value par rapport \u00e0 une pilule monophasique classique utilis\u00e9e en continu&#x002C; c.-\u00e0-d. sans interruption entre les cycles&#x002C; et son prix est nettement sup\u00e9rieur \u00e0 celui d\u2019une pilule monophasique classique pour une m\u00eame dur\u00e9e d\u2019utilisation.<\/p>\n<\/li>\n<li>\n<p>La sp\u00e9cialit\u00e9 <strong>Humalog<\/strong>\u00ae&#x002C; \u00e0 base d\u2019<strong>insuline<\/strong> <strong>lispro <\/strong>(chapitre 5.1.1.1.)&#x002C; d\u00e9j\u00e0 disponible en stylo injectable pr\u00e9-rempli \u00e0 une concentration de 100U\/ml&#x002C; est maintentant aussi disponible \u00e0 une concentration plus \u00e9lev\u00e9e de <strong>200 U\/ml<\/strong>. Cette forme plus concentr\u00e9e est destin\u00e9e aux patients n\u00e9cessitant des doses quotidiennes sup\u00e9rieures \u00e0 20 unit\u00e9s d\u2019insuline ultrarapide. Aucune conversion de dose ne doit \u00eatre effectu\u00e9e en cas de changement de concentration d\u2019Humalog\u00ae\u00a0; les stylos pr\u00e9-remplis sont en effet adapt\u00e9s \u00e0 la concentration&#x002C; et le nombre d\u2019unit\u00e9s \u00e0 administrer reste le m\u00eame. La solution d\u2019insuline lispro \u00e0 200 U\/ml ne peut donc \u00eatre administr\u00e9e qu\u2019au moyen du stylo pr\u00e9-rempli correspondant&#x002C; et elle ne peut en aucun cas \u00eatre transf\u00e9r\u00e9e dans un autre dispositif d\u2019administration. Afin de minimiser les risques d\u2019erreur et de confusion&#x002C; il est important d\u2019en informer les patients.<\/p>\n<\/li>\n<li>\n<p>Le remboursement de la <strong>pr\u00e9gabaline<\/strong> (<strong>Lyrica<\/strong>\u00ae&#x002C; chapitre 10.7.2.3.) dans l\u2019indication des douleurs neuropathiques ne se fait plus selon le chapitre IV mais selon le chapitre I (c.-\u00e0-d. sans autorisation pr\u00e9alable du m\u00e9decin conseil) (remboursement en cat\u00e9gorie b). En l\u2019absence de donn\u00e9es comparatives&#x002C; il n\u2019est pas facile de situer la place de la pr\u00e9gabaline par rapport aux antid\u00e9presseurs tricycliques et \u00e0 la gabapentine dans la prise en charge des douleurs neuropathiques. Son co\u00fbt est beaucoup plus \u00e9lev\u00e9 par rapport aux autres traitements [en ce qui concerne le traitement des douleurs neuropathiques&#x002C; voir la Fiche de transparence \u00ab\u00a0Prise en charge des douleurs neurog\u00e8nes\u00a0\u00bb et les Folia d\u2019avril 2006].<\/p>\n<\/li>\n<li>\n<p>Plusieurs changements sont survenus r\u00e9cemment dans les <strong>vaccins mis \u00e0 disposition gratuitement par les Communaut\u00e9s dans le cadre de la vaccination de base des enfants et des jeunes<\/strong>: voir tableau ci-dessous. Pour plus de d\u00e9tails&#x002C; nous renvoyons aux communiqu\u00e9s du 29\/06\/15 (concernant la Communaut\u00e9 flamande) et du 10\/09\/15 (concernant la Communaut\u00e9 fran\u00e7aise) dans la rubrique \u00ab\u00a0Bon \u00e0 savoir\u00a0\u00bb sur notre site Web. Vous y trouverez aussi quelques commentaires concernant le remplacement du Prevenar13\u00ae par Synflorix\u00ae en Communaut\u00e9 flamande (voir communiqu\u00e9 du 29\/06\/15) et concernant l\u2019indisponibilit\u00e9 temporaire du Tetravac\u00ae en Belgique (voir communiqu\u00e9 du 10\/09\/15).<\/p>\n<\/li>\n<\/ul>\n<table cellpadding='7' cellspacing='0' style='width:604px'>\n<tbody>\n<tr>\n<td>\n<p>En Communaut\u00e9 flamande<\/p>\n<\/td>\n<td>\n<p>En Communaut\u00e9 fran\u00e7aise<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li>\n<p>Priorix\u00ae est remplac\u00e9 par M.M.\u00a0R. Vax Pro\u00ae<\/p>\n<\/li>\n<li>\n<p>Infanrix-IPV\u00ae est remplac\u00e9 par Tetravac\u00ae<\/p>\n<\/li>\n<li>\n<p>Prevenar13\u00ae est remplac\u00e9 par Synflorix\u00a0\u00ae<\/p>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<\/td>\n<td>\n<ul>\n<li>\n<p>Infanrix Hexa\u00ae est remplac\u00e9 par\u00a0Hexyon\u00ae<\/p>\n<\/li>\n<li>\n<p>Menjugate\u00ae est remplac\u00e9 par\u00a0Neisvac-C\u00ae<\/p>\n<\/li>\n<li>\n<p>Imovax polio\u00ae et<\/p>\n<\/li>\n<\/ul>\n<p style='margin-left:1.26cm'>Tedivax pro adulto\u00ae ne sont plus mis \u00e0 disposition gratuitement.<\/p>\n<p>\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style='margin-left:1.26cm'> \u00a0<\/p>\n<p style='margin-left:1.26cm'> \u00a0<\/p>\n<p style='margin-left:1.26cm'> \u00a0<\/p>\n<p style='margin-left:1.26cm'> \u00a0<\/p>\n<p style='margin-left:1.26cm'> \u00a0<\/p>\n<div id='sdfootnote1'>\n<p><a class='sdfootnotesym' href='#sdfootnote1anc' name='sdfootnote1sym'>1<\/a><sup> Dimethyl fumarate. <em>Australian Prescriber<\/em> 2013&#x002C; 36Dim\u00e9thyle fumarate. Scl\u00e9rose en plaques\u00a0: trop d\u2019incertitude \u00e0 long terme. <em>La Revue Prescrire<\/em> 2014\u00a0; 34\u00a0: 813<\/sup><\/p>\n<p>Dimethyl fumarate for relapsing-remitting multiple sclerosis. <em>DTB<\/em> 2014; 52: 105-108<\/p>\n<p>Dimethylfumaraat een oude bekende nu geregistreerd bij multiple sclerose. <em>Pharma Selecta<\/em> 2013; 29:47-49<\/p>\n<p>\u00a0<\/p>\n<p> \u00a0<\/p>\n<\/p><\/div>\n<div id='sdfootnote2'>\n<p><a class='sdfootnotesym' href='#sdfootnote2anc' name='sdfootnote2sym'>2<\/a><sup> V\u00e9dolizumab. Pas de progr\u00e8s d\u00e9montr\u00e9 dans la maladie de Crohn ni dans la rectocolite h\u00e9morragique. <em>La Revue Prescrire<\/em> 2015\u00a0;35\u00a0: 263-264Vedolizumab\u00a0; monoklonale hoop voor de darmen. <em>Pharma Selecta<\/em> 2014\u00a0; 30\u00a0:68-71<\/sup><\/p>\n<p> \u00a0<\/p>\n<\/p><\/div>\n<div id='sdfootnote3'>\n<p><a class='sdfootnotesym' href='#sdfootnote3anc' name='sdfootnote3sym'>3<\/a><sup>A look at treatments for rosacea. <em>Worst Pills&#x002C; Best Pills<\/em> april 2015<\/sup><\/p>\n<\/p><\/div>\n<div id='sdfootnote4'>\n<p><a class='sdfootnotesym' href='#sdfootnote4anc' name='sdfootnote4sym'>4<\/a><sup>Umeclidinium: another LAMA for COPD. <em>DTB<\/em> 2015; 53: 81-4<\/sup><\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>: m\u00e9dicament soumis \u00e0 une surveillance particuli\u00e8re et pour lequel  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188135","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188135"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188135\/revisions"}],"predecessor-version":[{"id":190690,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188135\/revisions\/190690"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}