{"id":188107,"date":"2015-12-14T00:00:00","date_gmt":"2015-12-13T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/informations-recentes-decembre-2015-turoctocog-alfa-ledipasvir-sofosbuvir-nintedanib-idelalisib-olaparib\/"},"modified":"2026-08-27T15:11:19","modified_gmt":"2026-08-27T13:11:19","slug":"informations-recentes-decembre-2015-turoctocog-alfa-ledipasvir-sofosbuvir-nintedanib-idelalisib-olaparib","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/informations-recentes-decembre-2015-turoctocog-alfa-ledipasvir-sofosbuvir-nintedanib-idelalisib-olaparib\/","title":{"rendered":"Informations r\u00e9centes d\u00e9cembre 2015: turoctocog alfa, l\u00e9dipasvir + sofosbuvir, nint\u00e9danib, id\u00e9lalisib, olaparib"},"content":{"rendered":"<div class='tekst'>\n<table border='1' cellpadding='0' cellspacing='0'>\n<tbody>\n<tr>\n<td style='width:563px'>\n<p><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>: m\u00e9dicament soumis \u00e0 une surveillance particuli\u00e8re et \u00a0pour lequel la notification d\u2019effets ind\u00e9sirables au Centre Belge de Pharmacovigilance est encourag\u00e9e.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le <strong>turoctocog alfa<\/strong> (<strong>NovoEight<\/strong><strong>\u00ae<\/strong><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>&#x002C; chapitre 2.2.1.)\u00a0 est un analogue biosynth\u00e9tique du facteur VIII de coagulation qui a pour indication le traitement et la prophylaxie des \u00e9pisodes h\u00e9morragiques chez les patients atteints d\u2019h\u00e9mophilie A.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u2019association <strong>l\u00e9dipasvir + sofosbuvir<\/strong> (<strong>Harvoni<\/strong><strong>\u00ae<\/strong><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>&#x002C; chapitre 11.4.4.) est une association fixe d\u2019antiviraux \u00e0 action directe (c.-\u00e0-d. ciblant des \u00e9tapes sp\u00e9cifiques du cycle du virus de l\u2019h\u00e9patite C) qui a pour indication le traitement de l\u2019h\u00e9patite C chronique. Le sofosbuvir est un inhibiteur nucl\u00e9otidique de l\u2019ARN polym\u00e9rase du VHCqui existait d\u00e9j\u00e0 sous le nom de sp\u00e9cialit\u00e9 Sovaldi\u00d2. Le l\u00e9dipasvir est un inhibiteur de prot\u00e9ases sp\u00e9cifiques du VHC. Les principaux effets ind\u00e9sirables de cette association consistent en fatigue&#x002C; c\u00e9phal\u00e9es&#x002C; insomnie&#x002C; augmentation des lipases&#x002C; hypertension art\u00e9rielle et myalgies. Le l\u00e9dipasvir et le sofosbuvir sont des substrats de la P-gp\u00a0; le l\u00e9dipasvir est aussi un inhibiteur de la P-gp (<em>voir tableau Id dans l\u2019Introduction du R\u00e9pertoire<\/em>). Par ailleurs&#x002C; des bradycardies et des troubles de la conduction cardiaque ont \u00e9t\u00e9 rapport\u00e9s en cas de traitement concomitant avec l\u2019amiodarone. Comme avec les autres antiviraux \u00e0 action directe contre l\u2019h\u00e9patite C &#x002C; des r\u00e9sultats encourageants au niveau de la r\u00e9ponse virale ont \u00e9t\u00e9 rapport\u00e9s dans le cadre d\u2019\u00e9tudes cliniques (taux d\u2019\u00e9radication > 90%)&#x002C; mais ces \u00e9tudes n\u2019ont pas \u00e9t\u00e9 con\u00e7ues pour \u00e9valuer l\u2019efficacit\u00e9 sur les complications de l\u2019h\u00e9patite C&#x002C; et l\u2019innocuit\u00e9 \u00e0 long terme n\u2019est pas \u00e9tablie. Tenant compte du co\u00fbt tr\u00e8s \u00e9lev\u00e9 de ces traitements&#x002C; leur utilisation reste tr\u00e8s restreinte (<em>voir aussi Folia de septembre 2014)<\/em>.<a href='' name='_ftnref1' title=''>[1]<\/a><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le <strong>nint\u00e9danib<\/strong> (<strong>Ofev<\/strong><strong>\u00ae<\/strong><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>&#x002C; chapitre 13.7.) est un inhibiteur de tyrosine kinases qui a pour indication le traitement de la fibrose pulmonaire idiopathique. Ses principaux effets ind\u00e9sirables consistent en une diarrh\u00e9e&#x002C; des troubles gastro-intestinaux et une h\u00e9patotoxicit\u00e9. Dans les \u00e9tudes cliniques&#x002C; le nint\u00e9danib a entra\u00een\u00e9 une l\u00e9g\u00e8re am\u00e9lioration de la fonction respiratoire&#x002C; mais aucun effet n\u2019a \u00e9t\u00e9 d\u00e9montr\u00e9 sur l\u2019aggravation \u00e0 long terme de la fibrose&#x002C; ni sur la mortalit\u00e9. Il s\u2019agit d\u2019un m\u00e9dicament orphelin.<a href='' name='_ftnref2' title=''>[2]<\/a><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u2019<strong>id\u00e9lalisib<\/strong> (<strong>Zydelig<\/strong><strong>\u00ae<\/strong><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>&#x002C; chapitre 13.7.) est un inhibiteur de tyrosine kinases qui a pour indication le traitement de certaines formes de leuc\u00e9mie lympho\u00efde chronique et de lymphome folliculaire. L\u2019id\u00e9lalisib expose \u00e0 des effets ind\u00e9sirables\u00a0 parfois graves&#x002C; notamment digestifs avec diarrh\u00e9e et colite s\u00e9v\u00e8re&#x002C; h\u00e9patiques&#x002C; pulmonaires et cutan\u00e9s. L\u2019id\u00e9lalisib est un inhibiteur du CYP3A4 et un substrat de la P-gp (<em>voir tableau Ib et Id dans l\u2019Introduction du R\u00e9pertoire)<\/em>.<a href='' name='_ftnref3' title=''>[3]<\/a><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u2019<strong>olaparib <\/strong>(<strong>Lynparza<\/strong><strong>\u00ae<\/strong><img alt='' src='https:\/\/www.cbip.be\/images\/surv.gif' style='height:10px; width:10px' \/>&#x002C; chapitre 13.8.) est un inhibiteur des polym\u00e9rases qui a pour indication le traitement de certains cas avanc\u00e9s de cancer de l\u2019ovaire. L\u2019olaparid expose \u00e0 une toxicit\u00e9 h\u00e9matologique&#x002C; des troubles gastro-intestinaux&#x002C; de la dysgueusie et une t\u00e9ratog\u00e9nicit\u00e9. L\u2019olaparib est substrat du CYP3A4 et de la P-gp (<em>voir tableau Ib et Id dans l\u2019Introduction du R\u00e9pertoire)<\/em>. Il s\u2019agit d\u2019un m\u00e9dicament orphelin.<\/p>\n<div>\n<hr \/>\n<div id='ftn1'>\n<p><a href='' name='_ftn1' title=''>[1]<\/a><em>La Revue Prescrire<\/em>2015; 35: 732-8; <em>Australian prescriber <\/em>2015\u00a0; 38\u00a0:217-25<\/p>\n<\/p><\/div>\n<div id='ftn2'>\n<p><a href='' name='_ftn2' title=''>[2]<\/a><em>DTB<\/em>2015; 7: 78-81<\/p>\n<\/p><\/div>\n<div id='ftn3'>\n<p><a href='' name='_ftn3' title=''>[3]<\/a><em>La Revue Prescrire<\/em>2015; 35:808-9; <em>Pharma Selecta<\/em> 2015 (mai ) 6<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>: m\u00e9dicament soumis \u00e0 une surveillance particuli\u00e8re et \u00a0pour lequel  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,178],"tags":[20213,20224],"class_list":["post-188107","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2015-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188107"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188107\/revisions"}],"predecessor-version":[{"id":190662,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188107\/revisions\/190662"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}