{"id":188075,"date":"2016-06-07T00:00:00","date_gmt":"2016-06-06T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/choix-du-vaccin-contre-linfluenza-pour-la-saison-grippale-2016-2017\/"},"modified":"2026-08-27T15:11:18","modified_gmt":"2026-08-27T13:11:18","slug":"choix-du-vaccin-contre-linfluenza-pour-la-saison-grippale-2016-2017","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/choix-du-vaccin-contre-linfluenza-pour-la-saison-grippale-2016-2017\/","title":{"rendered":"Choix du vaccin contre l\u2019influenza pour la saison grippale 2016-2017"},"content":{"rendered":"<p><font face='Arial&#x002C; serif'><font size='3'>Comme chaque ann\u00e9e dans les Folia de juillet-ao\u00fbt&#x002C; des informations d\u00e9taill\u00e9es seront donn\u00e9es sur les vaccins contre l\u2019influenza pour la saison \u00e0 venir. En r\u00e9ponse \u00e0 plusieurs questions re\u00e7ues \u00e0 propos d\u2019\u00e9ventuels changements par rapport \u00e0 la saison pr\u00e9c\u00e9dente&#x002C; nous donnons d\u00e9j\u00e0 ici quelques informations succintes. <\/font><\/font><\/p>\n<p><font face='Arial&#x002C; serif'><font size='3'>La saison prochaine&#x002C; plusieurs vaccins trivalents et un vaccin t\u00e9travalent&#x002C; tous inactiv\u00e9s&#x002C; seront disponibles. Les vaccins trivalents contiendront une composante du virus de l\u2019influenza de type B de la ligne Victoria qui pr\u00e9dominait lors la saison grippale pr\u00e9c\u00e9dente&#x002C; au lieu d\u2019une composante B de la ligne Yamagata. Le vaccin t\u00e9travalent contiendra \u00e0 la fois une composante B de la ligne Victoria et de la ligne Yamagata. Le vaccin vivant pour la vaccination des enfants et adolescents ne sera pas disponible.<\/font><\/font><\/p>\n<p><font face='Arial&#x002C; serif'><font size='3'>Les informations que nous avons publi\u00e9es dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/2320?folia=2262'>Folia de juillet 2015<\/a> et <a href='https:\/\/www.cbip.be\/fr\/articles\/2568?folia=2563'>mars 2016<\/a> sont toujours valables.<\/font><\/font><\/p>\n<p lang='fr-BE'><font face='Arial&#x002C; serif'><font size='3'>Sur base de nos connaissances actuelles&#x002C; nous estimons que rien n\u2019indique que les populations \u00e0 risque lors de la saison grippale pr\u00e9c\u00e9dente \u00e9taient mieux prot\u00e9g\u00e9es contre une morbidit\u00e9 importante et une mortalit\u00e9 avec le vaccin t\u00e9travalent par rapport au vaccin trivalent&#x002C; \u00e0 la seule exception du petit groupe de jeunes enfants appartenant aux groupes \u00e0 risque (p.ex. enfants sous immunosuppresseurs). Comme nous l\u2019avons d\u00e9j\u00e0 signal\u00e9 pr\u00e9c\u00e9demment&#x002C; l\u2019influenza de type A a&#x002C; chez l\u2019adulte&#x002C; un impact plus important sur la morbidit\u00e9 s\u00e9v\u00e8re et la mortalit\u00e9 que l\u2019influenza de type B&#x002C; mais chez l\u2019enfant&#x002C; le poids de l\u2019infection par le virus de l\u2019influenza de type B est plus lourd que chez l\u2019adulte. Une immunit\u00e9 insuffisante contre l\u2019influenza de type B ne semble justifier la pr\u00e9f\u00e9rence pour un vaccin t\u00e9travalent que chez les jeunes enfants appartenant aux groupes \u00e0 risque et n\u2019ayant pas encore (ou presque pas) \u00e9t\u00e9 en contact avec l\u2019influenza de type B. Pour la plupart des groupes \u00e0 risque d\u2019adultes&#x002C; il n\u2019y a pas d\u2019argument d\u00e9cisif pour privil\u00e9gier sp\u00e9cifiquement un vaccin t\u00e9travalent.<\/font><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme chaque ann\u00e9e dans les Folia de juillet-ao\u00fbt&#x002C; des informations  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,177],"tags":[20213,20224],"class_list":["post-188075","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2016-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=188075"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188075\/revisions"}],"predecessor-version":[{"id":190630,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/188075\/revisions\/190630"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=188075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=188075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=188075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}