{"id":187589,"date":"2021-01-26T00:00:00","date_gmt":"2021-01-25T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/guide-bapcoc-pour-la-pratique-ambulatoire-mise-a-jour-2021-dans-notre-repertoire-en-ligne-et-desormais-egalement-disponible-en-format-pdf\/"},"modified":"2026-08-27T15:11:01","modified_gmt":"2026-08-27T13:11:01","slug":"guide-bapcoc-pour-la-pratique-ambulatoire-mise-a-jour-2021-dans-notre-repertoire-en-ligne-et-desormais-egalement-disponible-en-format-pdf","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/guide-bapcoc-pour-la-pratique-ambulatoire-mise-a-jour-2021-dans-notre-repertoire-en-ligne-et-desormais-egalement-disponible-en-format-pdf\/","title":{"rendered":"Guide BAPCOC pour la pratique ambulatoire : mise \u00e0 jour 2021 dans notre R\u00e9pertoire en ligne et d\u00e9sormais \u00e9galement disponible en format PDF"},"content":{"rendered":"<p>Le \u201c<b>Guide belge de traitement anti-infectieux en pratique ambulatoire<\/b>\u201d de la Commission Belge de Coordination de la Politique Antibiotique (<b>BAPCOC<\/b>) vient d&#39;\u00eatre mis \u00e0 jour: <b>\u00e9dition 2021<\/b>. Cette \u00e9dition mise \u00e0 jour est int\u00e9gralement disponible:<\/p>\n<ul>\n<li>\n<p>dans la version <strong>en ligne<\/strong> du R\u00e9pertoire comment\u00e9 des M\u00e9dicaments&#x002C; dans le chapitre <strong><a href='https:\/\/www.cbip.be\/fr\/chapters\/12?frag=8000010'>11.5. BAPCOC \u2013 Guide belge de traitement anti-infectieux en pratique ambulatoire &#8211; 2021.<\/a><\/strong><\/p>\n<\/li>\n<li>\n<p>en <strong>format PDF imprimable<\/strong>: cliquez <a href='https:\/\/www.health.belgium.be\/sites\/default\/files\/uploads\/fields\/fpshealth_theme_file\/guide_belge_bapcoc_fr_2021_a4_0.pdf'>ici<\/a><\/p>\n<\/li>\n<\/ul>\n<p>Les renvois au \u201cGuide belge de traitement anti-infectieux en pratique ambulatoire\u201d dans les rubriques \u201c<strong>Positionnement<\/strong>\u201d des <em>chapitres Infections&#x002C; Gyn\u00e9co-obst\u00e9trique&#x002C; Dermatologie <\/em>et<em> Oto-Rhino-Laryngologie<\/em> seront mis \u00e0 jour d\u00e8s le 20 f\u00e9vrier 2021.<\/p>\n<p> Le Guide BAPCOC fait le point sur les connaissances scientifiques actuelles concernant l\u2019utilit\u00e9 et l\u2019efficacit\u00e9 des m\u00e9dicaments anti-infectieux dans le traitement des infections courantes en pratique ambulatoire. Ces informations sont adapt\u00e9es au contexte belge&#x002C; ce qui est particuli\u00e8rement important pour l&#39;utilisation des antibiotiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le \u201cGuide belge de traitement anti-infectieux en pratique ambulatoire\u201d de  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,31],"tags":[20213,20224],"class_list":["post-187589","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2021-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187589"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187589\/revisions"}],"predecessor-version":[{"id":190144,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187589\/revisions\/190144"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}