{"id":187587,"date":"2021-01-28T00:00:00","date_gmt":"2021-01-27T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/problemes-de-telechargement-du-rcp-et-de-la-notice-patients-sur-le-site-web-du-cbip\/"},"modified":"2026-08-27T15:11:01","modified_gmt":"2026-08-27T13:11:01","slug":"problemes-de-telechargement-du-rcp-et-de-la-notice-patients-sur-le-site-web-du-cbip","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/problemes-de-telechargement-du-rcp-et-de-la-notice-patients-sur-le-site-web-du-cbip\/","title":{"rendered":"Probl\u00e8mes de t\u00e9l\u00e9chargement du RCP et de la notice patients sur le site Web du CBIP"},"content":{"rendered":"<p>De nombreux lecteurs nous interrogent en ce moment au sujet du t\u00e9l\u00e9chargement du RCP et de la notice patients dans notre R\u00e9pertoire en ligne.\u00a0<\/p>\n<p> En raison d\u2019un concours de circonstances \u2013 malheureusement ind\u00e9pendantes de notre volont\u00e9 \u2013 ce t\u00e9l\u00e9chargement pose en effet des probl\u00e8mes pour le moment.<\/p>\n<ul>\n<li>\n<p>Le premier probl\u00e8me est d\u00fb \u00e0 une mise \u00e0 jour du navigateur Google Chrome dont les nouveaux param\u00e8tres de s\u00e9curit\u00e9 bloquent le t\u00e9l\u00e9chargement de fichiers h\u00e9berg\u00e9s sur un autre nom de domaine non s\u00e9curis\u00e9 (http).<\/p>\n<\/li>\n<li>\n<p>Le deuxi\u00e8me probl\u00e8me vient du fait que les notices ne sont pas h\u00e9berg\u00e9es chez nous&#x002C; elles sont la propri\u00e9t\u00e9 de l&#39;AFMPS et lorsque vous cliquez sur un symbole \u00ab\u00a0g\u00e9lule bleue\u00a0\u00bb&#x002C; vous \u00eates redirig\u00e9s par un lien direct vers le PDF h\u00e9berg\u00e9 sur\u00a0<a href='https:\/\/notices.afmps-fagg.be\/' target='_blank'>notices.afmps-fagg.be<\/a>\u00a0qui ne poss\u00e8de pas de certificat de cryptage (et donc non s\u00e9curis\u00e9)&#x002C; ce qui d\u00e9clenche le blocage par Google Chrome.<br \/> Ce probl\u00e8me a \u00e9t\u00e9 signal\u00e9 \u00e0 l\u2019AFMPS qui s\u2019efforce d\u2019y rem\u00e9dier.<\/p>\n<\/li>\n<\/ul>\n<p>En attendant que ce probl\u00e8me soit r\u00e9solu&#x002C; vous pouvez soit :\u00a0<\/p>\n<ul>\n<li>\n<p>utiliser un autre navigateur (Firefox&#x002C; Edge&#x002C; &#8230;).<\/p>\n<\/li>\n<li>\n<p><span class='VIiyi' jsaction='mouseup:BR6jm' jsname='jqKxS' lang='fr'><span class='JLqJ4b ChMk0b' data-language-for-alternatives='fr' data-language-to-translate-into='nl' data-phrase-index='0' jsaction='agoMJf:PFBcW;usxOmf:aWLT7;jhKsnd:P7O7bd&#x002C;F8DmGf;Q4AGo:Gm7gYd&#x002C;qAKMYb;uFUCPb:pvnm0e&#x002C;pfE8Hb&#x002C;PFBcW;f56efd:dJXsye;EnoYf:KNzws&#x002C;ZJsZZ&#x002C;JgVSJc;zdMJQc:cCQNKb&#x002C;ZJsZZ&#x002C;zchEXc;Ytrrj:JJDvdc;tNR8yc:GeFvjb;oFN6Ye:hij5Wb' jscontroller='Zl5N8' jsdata='uqLsIf;_;$20' jsmodel='SsMkhd' jsname='txFAF'><span jsaction='click:qtZ4nf&#x002C;GFf3ac&#x002C;tMZCfe; contextmenu:Nqw7Te&#x002C;QP7LD; mouseout:Nqw7Te; mouseover:qtZ4nf&#x002C;c2aHje' jsname='W297wb'>soit&#x002C; si vous optez de continuer \u00e0 travailler avec Google Chrome<\/span><\/span><\/span> : faire un clic-droit sur la \u00ab\u00a0g\u00e9lule bleue\u00a0\u00bb et s\u00e9lectionner &lsquo;Ouvrir le lien dans un nouvel onglet&rsquo;. Le document est alors automatiquement t\u00e9l\u00e9charg\u00e9 et vous pouvez l\u2019ouvrir en cliquant sur le fichier qui s&#39;affiche au bas de la fen\u00eatre Chrome.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>De nombreux lecteurs nous interrogent en ce moment au sujet  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,31],"tags":[20213,20224],"class_list":["post-187587","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2021-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187587"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187587\/revisions"}],"predecessor-version":[{"id":190142,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187587\/revisions\/190142"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}