{"id":187547,"date":"2021-04-15T00:00:00","date_gmt":"2021-04-14T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/vaccin-covid-19-dastrazeneca-et-evenements-thrombotiques-associes-a-une-thrombopenie-sources-dinformations-complementaires\/"},"modified":"2026-08-27T15:11:00","modified_gmt":"2026-08-27T13:11:00","slug":"vaccin-covid-19-dastrazeneca-et-evenements-thrombotiques-associes-a-une-thrombopenie-sources-dinformations-complementaires","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/vaccin-covid-19-dastrazeneca-et-evenements-thrombotiques-associes-a-une-thrombopenie-sources-dinformations-complementaires\/","title":{"rendered":"Vaccin COVID-19 d\u2019AstraZeneca et \u00e9v\u00e9nements thrombotiques associ\u00e9s \u00e0 une thrombop\u00e9nie: sources d\u2019informations compl\u00e9mentaires"},"content":{"rendered":"<p>Les cas d&#39;\u00e9v\u00e9nements thrombotiques associ\u00e9s \u00e0 une thrombop\u00e9nie qui ont \u00e9t\u00e9 rapport\u00e9s suite \u00e0 la vaccination avec le vaccin AstraZeneca (Vaxzevria\u00ae&#x002C; auparavant appel\u00e9 COVID-19 Vaccine AstraZeneca\u00ae) continuent de susciter des questions et de faire l\u2019objet de discussions. Nous avons abord\u00e9 ces \u00e9v\u00e9nements dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/3590?folia=3562'>Folia d&#39;avril 2021<\/a> et dans notre <a href='https:\/\/www.cbip.be\/fr\/gows\/3593'>communiqu\u00e9 Bon \u00e0 savoir du 09\/04\/21<\/a>. Il s\u2019agit d\u2019\u00e9v\u00e9nements tr\u00e8s rares; un lien de causalit\u00e9 ne peut \u00eatre exclu. Pour des informations plus d\u00e9taill\u00e9es sur ces \u00e9v\u00e9nements&#x002C; nous renvoyons notamment aux sources suivantes:<\/p>\n<ul>\n<li>\n<p><strong><a href='https:\/\/www.bsth.be\/about-bsth'>Site Web de la Soci\u00e9t\u00e9 Belge de Thrombose et H\u00e9mostase<\/a><\/strong> (<em>Belgian Society on Thrombosis and Haemostasis<\/em>&#x002C; BSTH). Un <a href='https:\/\/www.bsth.be\/application\/files\/4116\/1796\/3826\/BSTH_VIPIT_algorithms_FR_v1.pdf'>document questions-r\u00e9ponses&#x002C; adress\u00e9 aux professionnels de la sant\u00e9 (version 09\/04\/21)<\/a>&#x002C; r\u00e9sume les informations&#x002C; avec des explications concernant la fr\u00e9quence&#x002C; le m\u00e9canisme&#x002C; les sympt\u00f4mes&#x002C; les \u00e9tudes utiles et les principes de traitement. Dans un autre <a href='https:\/\/www.bsth.be\/application\/files\/9016\/1719\/6991\/BSTH_COVID-19_vaccination_FR_20210331.pdf'>document questions-r\u00e9ponses&#x002C; adress\u00e9 au grand public (version 31\/03\/21)<\/a>&#x002C; les experts de la BSTH r\u00e9pondent aux questions les plus fr\u00e9quemment pos\u00e9es sur les vaccins COVID-19 et la thrombose.<\/p>\n<\/li>\n<li>\n<p>Deux publications dans le <strong><em>New England Journal of Medicine<\/em> (09\/04\/21)<\/strong> d\u00e9crivent en d\u00e9tail un certain nombre de patients ayant d\u00e9velopp\u00e9 des \u00e9v\u00e9nements thrombotiques associ\u00e9s \u00e0 une thrombop\u00e9nie apr\u00e8s avoir \u00e9t\u00e9 vaccin\u00e9s avec le vaccin AstraZeneca : <strong><a href='https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMoa2104882'>Schulz et al.<\/a><\/strong> concernant 5 patients en Norv\u00e8ge&#x002C; et <strong><a href='https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMoa2104840'>Greinacher et al.<\/a><\/strong> concernant 11 patients en Autriche et en Allemagne. Ces s\u00e9ries de cas ne permettent pas de d\u00e9terminer l&#39;incidence ni d&#39;\u00e9tablir un lien de causalit\u00e9 [<a href='https:\/\/www.bmj.com\/content\/373\/bmj.n954'>Brit Med J&#x002C; 12\/04\/21<\/a>].<\/p>\n<\/li>\n<li>\n<p><em><a href='https:\/\/www.afmps.be\/sites\/default\/files\/DHPC%20Vaxzevria-Covid-19%20FR%20-%20Website.pdf'>Direct Healthcare Professional Communication (DHPC)&#x002C; publi\u00e9e sur le site Web de l&#39;AFMPS le 13\/04\/21<\/a><\/em>: \u00ab\u00a0VAXZEVRIA\/COVID-19 Vaccine AstraZeneca: lien entre le vaccin et la survenue de thrombose en association avec une thrombocytop\u00e9nie.\u00a0\u00bb<\/p>\n<\/li>\n<\/ul>\n<p> Le 13\/04\/21&#x002C; des messages sont publi\u00e9s faisant \u00e9tat de <strong>quelques cas de thrombose veineuse c\u00e9r\u00e9brale<\/strong> ayant \u00e9t\u00e9 rapport\u00e9s aux \u00c9tats-Unis avec le <strong>vaccin Janssen<\/strong> (Janssen COVID-19 Vaccine\u00ae&#x002C; \u00e9galement appel\u00e9 vaccin de Johnson&#038;Johnson). 6 cas ont \u00e9t\u00e9 rapport\u00e9s&#x002C; sur environ 6&#x002C;8 millions de doses administr\u00e9es. Nous renvoyons au site Web des CDC pour un <strong>communiqu\u00e9 commun de la FDA et des CDC<\/strong> (<a href='https:\/\/www.cdc.gov\/media\/releases\/2021\/s0413-JJ-vaccine.html'>communiqu\u00e9 du 13\/04\/21<\/a>). L&#39;Agence europ\u00e9enne des m\u00e9dicaments <strong>EMA<\/strong> proc\u00e8de \u00e0 l\u2019\u00e9valuation de ces cas et pr\u00e9voit de publier une recommandation au cours de la semaine du 19 avril (<a href='https:\/\/www.ema.europa.eu\/en\/news\/covid-19-vaccine-janssen-assessment-very-rare-cases-unusual-blood-clots-low-platelets-continues'>communiqu\u00e9 du 14\/04\/21<\/a>). En attendant&#x002C; aucun vaccin Janssen n&#39;est administr\u00e9. Nous ferons un rapport plus d\u00e9taill\u00e9 lorsque de plus amples informations seront disponibles.<br \/> \u00a0<br \/> <strong>Note. <\/strong>Pour tous nos articles relatifs aux m\u00e9dicaments dans la COVID-19: voir les\u00a0<u><a href='https:\/\/www.cbip.be\/fr\/gows\/3334'>Actualit\u00e9s COVID-19\u00a0<\/a><\/u>sur notre site Web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les cas d&#39;\u00e9v\u00e9nements thrombotiques associ\u00e9s \u00e0 une thrombop\u00e9nie qui ont  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,31],"tags":[48,20213,20224,20226],"class_list":["post-187547","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2021-fr","tag-actualites-covid-19","tag-import_tags","tag-import_tags-nl","tag-covid-19-update"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187547"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187547\/revisions"}],"predecessor-version":[{"id":190102,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187547\/revisions\/190102"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}