{"id":187519,"date":"2021-06-09T00:00:00","date_gmt":"2021-06-08T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/covid-19-autorisation-du-vaccin-pfizer-comirnaty-etendue-aux-12-a-15-ans-en-europe\/"},"modified":"2026-08-27T15:10:58","modified_gmt":"2026-08-27T13:10:58","slug":"covid-19-autorisation-du-vaccin-pfizer-comirnaty-etendue-aux-12-a-15-ans-en-europe","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/covid-19-autorisation-du-vaccin-pfizer-comirnaty-etendue-aux-12-a-15-ans-en-europe\/","title":{"rendered":"COVID-19: autorisation du vaccin Pfizer (Comirnaty\u00ae) \u00e9tendue aux 12 \u00e0 15 ans en Europe"},"content":{"rendered":"<p>Apr\u00e8s la <em>Food and Drug Administration<\/em> (FDA) am\u00e9ricaine&#x002C; l&#39;<a href='https:\/\/www.ema.europa.eu\/en\/news\/first-covid-19-vaccine-approved-children-aged-12-15-eu'>Agence europ\u00e9enne des m\u00e9dicaments (EMA)<\/a> donne elle aussi un avis favorable \u00e0 l&#39;utilisation de Comirnaty\u00ae (vaccin Pfizer) chez les adolescents \u00e2g\u00e9s de 12 \u00e0 15 ans.<span class='folia-referentie-note'><strong><sup>1<\/sup><\/strong><\/span> Le vaccin Pfizer \u00e9tait d\u00e9j\u00e0 autoris\u00e9 \u00e0 partir de l&#39;\u00e2ge de 16 ans. Les autres vaccins COVID-19 (COVID-19 Vaccine Moderna\u00ae&#x002C; Vaxzevria\u00ae&#x002C; Janssen COVID-19 Vaccine\u00ae) sont autoris\u00e9s \u00e0 partir de l&#39;\u00e2ge de 18 ans.<br \/> \u00a0<br \/> L&#39;autorisation du vaccin Pfizer a \u00e9t\u00e9 \u00e9tendue aux jeunes de 12 \u00e0 15 ans suite aux r\u00e9sultats d&#39;une \u00e9tude contr\u00f4l\u00e9e randomis\u00e9e men\u00e9e aux \u00c9tats-Unis aupr\u00e8s d&#39;<strong>environ 2 200 adolescents de 12 \u00e0 15 ans<\/strong>. Il s&#39;agit d&#39;une <strong>extension de l&#39;\u00e9tude de phase II\/III<\/strong> dont les r\u00e9sultats concernant les personnes \u00e2g\u00e9es de 16 ans et plus ont \u00e9t\u00e9 publi\u00e9s dans le NEJM et discut\u00e9s dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/3518?folia=3503'>Folia de janvier 2021<\/a>. Les <strong>r\u00e9sultats concernant les jeunes de 12 \u00e0 15 ans<\/strong> ont \u00e9t\u00e9 <strong>publi\u00e9s dans le NEJM<\/strong> le 27\/05\/21.<span class='folia-referentie-note'><sup> 2<\/sup><\/span> L&#39;EMA (RCP) et la FDA fournissent \u00e9galement des informations d\u00e9taill\u00e9es.<span class='folia-referentie-note'><sup> 3&#x002C;4<\/sup><\/span><\/p>\n<h2>Quelques d\u00e9tails concernant le profil d\u2019efficacit\u00e9 et d\u2019innocuit\u00e9 (\u00e9tude de phase II\/III)<\/h2>\n<ul>\n<li>\n<p><strong>Sch\u00e9ma de vaccination\u00a0: <\/strong>2 injections intramusculaires \u00e0 21 jours d\u2019intervalle.<\/p>\n<\/li>\n<li>\n<p>La <strong>protection contre la COVID-19 symptomatique&#x002C; confirm\u00e9e par PCR&#x002C; au moins 7 jours apr\u00e8s la 2<sup>e<\/sup> dose <\/strong>(crit\u00e8re d&#39;\u00e9valuation primaire&#x002C; analyse chez les personnes <em>sans<\/em> preuve d\u2019une infection ant\u00e9rieure par le SARS-CoV2) \u00e9tait de 100 % (IC \u00e0 95% de 75&#x002C;3 \u00e0 100). Il y a eu 0 cas de COVID-19 sur 1 005 personnes dans le groupe ayant re\u00e7u le vaccin COVID-19&#x002C; contre 16 cas sur 978 personnes dans le groupe placebo.<\/p>\n<div class='detailed-content'>\n<ul>\n<li>Le m\u00eame degr\u00e9 de protection de 100% \u00e9tait obtenu lorsque les personnes <em>avec<\/em> preuve d\u2019une infection ant\u00e9rieure par le SARS-CoV2 \u00e9taient incluses dans l&#39;analyse (environ 100 personnes suppl\u00e9mentaires dans chacun des deux groupes)\u00a0: 0 cas de COVID-19 sur 1\u00a0119 personnes dans le groupe ayant re\u00e7u le vaccin COVID-19&#x002C; contre 18 cas sur 1\u00a0110 personnes dans le groupe placebo.<\/li>\n<li>Aucun cas grave de COVID-19 n\u2019a \u00e9t\u00e9 rapport\u00e9.<\/li>\n<\/ul><\/div>\n<\/li>\n<li>\n<p>La <strong>r\u00e9ponse immunitaire<\/strong> (titre d&#39;anticorps 1 mois apr\u00e8s la 2<sup>e<\/sup> dose&#x002C; mesur\u00e9 dans un \u00e9chantillon al\u00e9atoire de sujets de l&#39;\u00e9tude de phase II\/III) \u00e9tait plus \u00e9lev\u00e9e chez les 12-15 ans (n=190) que chez les 16-25 ans (n=170)&#x002C; et r\u00e9pondait aux crit\u00e8res pr\u00e9d\u00e9finis de \u00ab\u00a0non-inf\u00e9riorit\u00e9\u00a0\u00bb.\u00a0<\/p>\n<\/li>\n<li>\n<p><strong>Effets ind\u00e9sirables <\/strong>(suivi pendant au moins 2 mois apr\u00e8s la 2<sup>e<\/sup> dose)\u00a0:<\/p>\n<ul>\n<li>\n<div>Douleur au point d&#39;injection apr\u00e8s la 1<sup>e<\/sup> dose : 86% dans le groupe vaccin\u00e9 contre 23% dans le groupe placebo. Le taux d&#39;incidence \u00e9tait l\u00e9g\u00e8rement moins \u00e9lev\u00e9 apr\u00e8s la 2<sup>e<\/sup> dose.<\/div>\n<\/li>\n<li>\n<div>Effets syst\u00e9miques apr\u00e8s la 1<sup>e<\/sup> dose (groupe vaccin\u00e9 vs groupe placebo) : fatigue (60% vs 41%)&#x002C; c\u00e9phal\u00e9es (55% vs 35%)&#x002C; frissons (28% vs 10%)&#x002C; douleurs musculaires (24% vs 13%)&#x002C; fi\u00e8vre (10% vs 1%)&#x002C; douleurs articulaires (10% vs 7%). Les taux d\u2019incidence \u00e9taient l\u00e9g\u00e8rement plus \u00e9lev\u00e9s apr\u00e8s la 2<sup>e<\/sup> dose.<\/div>\n<\/li>\n<li>\n<div>Ces effets \u00e9taient g\u00e9n\u00e9ralement l\u00e9gers \u00e0 mod\u00e9r\u00e9s&#x002C; et disparaissaient dans les 2 jours.<\/div>\n<\/li>\n<li>\n<div>Les taux d\u2019incidence sont comparables aux taux d\u2019incidence chez les 16-25 ans. Ils sont \u00e9galement comparables aux taux d\u2019incidence dans le groupe plus large des 16-55 ans [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/3518?folia=3503'>Folia de janvier 2021<\/a>].<\/div>\n<\/li>\n<li>\n<div>Lymphad\u00e9nopathie : 0&#x002C;8 % dans le groupe vaccin\u00e9 contre 0&#x002C;2 % dans le groupe placebo. Cette r\u00e9action \u00e9tait plus fr\u00e9quente que chez les 16-25 ans.<\/div>\n<\/li>\n<li>\n<div>Aucune r\u00e9action anaphylactique n&#39;a \u00e9t\u00e9 observ\u00e9e.<\/div>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2>Quelques commentaires<\/h2>\n<ul>\n<li>\n<p>L&#39;EMA<span class='folia-referentie-note'><strong><sup>1&#x002C;4<\/sup><\/strong><\/span> et la FDA<span class='folia-referentie-note'><strong><sup>5<\/sup><\/strong><\/span> \u00e9valuent actuellement un <strong>signal de p\u00e9ricardite et de myocardite apr\u00e8s l&#39;administration des vaccins \u00e0 ARNm<\/strong> (vaccin Pfizer&#x002C; vaccin Moderna). Cette \u00e9valuation fait suite aux quelques cas qui ont \u00e9t\u00e9 rapport\u00e9s&#x002C; principalement chez des adolescents et des jeunes adultes de sexe masculin. Un lien de causalit\u00e9 n&#39;a pas \u00e9t\u00e9 \u00e9tabli \u00e0 ce jour. <strong>Nous y reviendrons d\u00e8s que nous aurons de plus amples informations<\/strong>.<\/p>\n<\/li>\n<li>\n<p>Le Conseil Sup\u00e9rieur de la Sant\u00e9 (CSS) belge n&#39;a pas encore formul\u00e9 de recommandation concernant la vaccination contre la COVID-19 des jeunes de 12 \u00e0 15 ans (situation au 07\/06\/21).<\/p>\n<\/li>\n<li>\n<p><strong>Commentaire du CBIP. <\/strong>La d\u00e9cision d&#39;inclure les jeunes de 12 \u00e0 15 ans comme groupe cible pour la vaccination contre la COVID-19 doit reposer sur une \u00e9valuation du rapport risque\/b\u00e9n\u00e9fice&#x002C; en tenant compte des \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<ul>\n<li>\n<p>Dans cette jeune tranche d\u2019\u00e2ge&#x002C; le b\u00e9n\u00e9fice individuel \u00e0 attendre de la vaccination est limit\u00e9&#x002C; le risque de d\u00e9velopper une forme grave de COVID-19 \u00e9tant tr\u00e8s faible.<\/p>\n<\/li>\n<li>\n<p>D&#39;un c\u00f4t\u00e9&#x002C; plus le pourcentage de personnes vaccin\u00e9es augmente dans les groupes adultes&#x002C; moins les 12-15 ans contribuent \u00e0 \u00ab\u00a0l\u2019immunit\u00e9 de groupe\u00a0\u00bb. D\u2019un autre c\u00f4t\u00e9&#x002C; l&#39;immunit\u00e9 de groupe requiert un pourcentage de personnes vaccin\u00e9es d\u2019autant plus \u00e9lev\u00e9 qu\u2019il y a de variants contagieux (le variant Gamma br\u00e9silien et Delta indien ; peut-\u00eatre aussi des variants plus r\u00e9cents) dans une population.<\/p>\n<\/li>\n<li>\n<p>Le signal de p\u00e9ricardite et de myocardite&#x002C; bien que la causalit\u00e9 reste incertaine&#x002C; doit \u00eatre pris en compte dans cette \u00e9valuation.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u00a0<br \/> <strong>Note.<\/strong> Pour tous nos articles relatifs aux m\u00e9dicaments dans la COVID-19: voir <a href='https:\/\/www.cbip.be\/fr\/gows\/3334'>Actualit\u00e9s COVID-19<\/a>.<br \/> \u00a0<\/p>\n<h2>Sources sp\u00e9cifiques<\/h2>\n<div class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1.\u00a0 <\/span>EMA: First COVID-19 vaccine approved for children aged 12 to 15 in EU. <a href='https:\/\/www.ema.europa.eu\/en\/news\/first-covid-19-vaccine-approved-children-aged-12-15-eu'>News 28\/05\/21<\/a>.<br \/> <span class='folia-referentie-nummer'>2.\u00a0<\/span> Frenck RW&#x002C; Klein NP&#x002C; Kitchin N. Safety&#x002C; Immunogenicity&#x002C; and Efficacy of the BNT162b2 Covid-19 Vaccine in Adolescents. NEJM&#x002C; online op 27\/05\/21. Doi: <a href='https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMoa2107456'>10.1056\/NEJMoa2107456<\/a><br \/> <span class='folia-referentie-nummer'>3.\u00a0<\/span> EMA: SKP Comirnaty\u00ae. Via l\u2019<a href='https:\/\/www.ema.europa.eu\/en\/medicines\/human\/EPAR\/comirnaty'>EPAR<\/a>.<br \/> <span class='folia-referentie-nummer'>4.\u00a0<\/span> FDA: Coronavirus (COVID-19) Update: FDA Authorizes Pfizer-BioNTech COVID-19 Vaccine for Emergency Use in Adolescents in Another Important Action in Fight Against Pandemic. <a href='https:\/\/www.fda.gov\/news-events\/press-announcements\/coronavirus-covid-19-update-fda-authorizes-pfizer-biontech-covid-19-vaccine-emergency-use'>News release 10\/05\/21<\/a>&#x002C; et <a href='https:\/\/www.fda.gov\/media\/144413\/download'>FACT SHEET FOR HEALTHCARE PROVIDERS ADMINISTERING VACCINE<\/a>.<br \/> <span class='folia-referentie-nummer'>5.\u00a0 <\/span>EMA&#x002C; <a href='https:\/\/www.ema.europa.eu\/en\/news\/meeting-highlights-pharmacovigilance-risk-assessment-committee-prac-3-6-may-2021'>News 07\/05\/21<\/a>.<br \/> <span class='folia-referentie-nummer'>6.\u00a0 <\/span>FDA&#x002C; <a href='https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/vaccines\/safety\/adverse-events.html'>update du 27\/05\/21<\/a> et <a href='https:\/\/www.cdc.gov\/vaccines\/covid-19\/clinical-considerations\/myocarditis.html'>update du 28\/05\/21<\/a><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s la Food and Drug Administration (FDA) am\u00e9ricaine&#x002C; l&#39;Agence europ\u00e9enne  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,31],"tags":[48,20213,20224,20226],"class_list":["post-187519","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2021-fr","tag-actualites-covid-19","tag-import_tags","tag-import_tags-nl","tag-covid-19-update"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187519"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187519\/revisions"}],"predecessor-version":[{"id":190074,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187519\/revisions\/190074"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}