{"id":186694,"date":"2021-12-01T00:00:00","date_gmt":"2021-11-30T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/signaux-de-mesusage-de-la-pregabaline-aussi-en-belgique\/"},"modified":"2026-08-27T15:10:31","modified_gmt":"2026-08-27T13:10:31","slug":"signaux-de-mesusage-de-la-pregabaline-aussi-en-belgique","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/signaux-de-mesusage-de-la-pregabaline-aussi-en-belgique\/","title":{"rendered":"Signaux de m\u00e9susage de la pr\u00e9gabaline, aussi en Belgique"},"content":{"rendered":"<p>En <a href='https:\/\/www.cbip.be\/fr\/articles\/3259?folia=3257'>f&eacute;vrier 2020&#x002C; les Folia<\/a> attiraient l&rsquo;attention sur le risque d&rsquo;abus et d&rsquo;effets ind&eacute;sirables avec la pr&eacute;gabaline et la gabapentine&#x002C; deux anti&eacute;pileptiques autoris&eacute;s pour le traitement de l&rsquo;&eacute;pilepsie et des douleurs neuropathiques. Dans le RCP de la pr&eacute;gabaline&#x002C; le trouble anxieux g&eacute;n&eacute;ralis&eacute; figure &eacute;galement parmi les indications. Ces deux m&eacute;dicaments sont de plus en plus souvent utilis&eacute;s <em>off-label <\/em>dans les douleurs chroniques non neuropathiques (notamment lombalgies&#x002C; sciatique&#x002C; syndrome du canal carpien et prophylaxie de la migraine)&#x002C; bien que l&rsquo;efficacit&eacute; dans ces indications ne soit pas prouv&eacute;e&nbsp;[<a href='https:\/\/www.cbip.be\/fr\/articles\/2836?folia=2834'>voir Folia f&eacute;vrier 2018<\/a>]. On mentionnait dans l&rsquo;article des <a href='https:\/\/www.cbip.be\/fr\/articles\/3259?folia=3257'>Folia de f&eacute;vrier 2020<\/a> que le nombre de cas d&rsquo;abus avait particuli&egrave;rement augment&eacute; ces derni&egrave;res ann&eacute;es aux Etats-Unis&#x002C; en France et au Royaume-Uni.<\/p>\n<p><b>En Belgique<\/b>&#x002C; les services d&rsquo;inspection de l&rsquo;Agence f&eacute;d&eacute;rale des m&eacute;dicaments et des produits de sant&eacute; (AFMPS) constatent aussi <b>une augmentation des cas de m&eacute;susage avec la pr&eacute;gabaline<\/b> (Lyrica&reg; et g&eacute;n&eacute;riques) rapport&eacute;s par les gens de terrain (essentiellement par des pharmaciens). Il s&rsquo;agit surtout de patients tentant d&rsquo;obtenir ce m&eacute;dicament &agrave; l&rsquo;aide de fausses prescriptions ou en consultant plusieurs m&eacute;decins pour obtenir des prescriptions (shopping m&eacute;dical). Le m&eacute;susage de pr&eacute;gabaline est souvent associ&eacute; &agrave; un m&eacute;susage d&rsquo;autres m&eacute;dicaments s&eacute;datifs.<\/p>\n<p>L&rsquo;<b>agence fran&ccedil;aise de s&eacute;curit&eacute; des m&eacute;dicaments (ANSM)<\/b> a aussi attir&eacute; l&rsquo;attention via un <a href='https:\/\/ansm.sante.fr\/actualites\/pregabaline-lyrica-et-generiques-modification-des-conditions-de-prescription-et-delivrance-pour-limiter-le-mesusage'>communiqu&eacute; (publi&eacute; le 24\/02\/2021&#x002C; mis &agrave; jour le 21\/05\/2021)<\/a> sur une augmentation importante des cas d&rsquo;addiction et d&rsquo;abus avec la pr&eacute;gabaline <b>en France<\/b> (r&eacute;sultats d&rsquo;enqu&ecirc;tes d&rsquo;addictovigilance)&nbsp;:<\/p>\n<ul>\n<li>\n<p>234 d&eacute;clarations d&rsquo;abus&#x002C; de d&eacute;pendance et d&rsquo;usage d&eacute;tourn&eacute; en 2019&#x002C; contre 106 en 2018 et 18 en 2016 (majoritairement des hommes&#x002C; &acirc;ge moyen&nbsp;: 27 ans).<\/p>\n<\/li>\n<li>\n<p>Les patients prenaient souvent d&rsquo;autres m&eacute;dicaments&#x002C; notamment une benzodiaz&eacute;pine et\/ou un opio&iuml;de.<\/p>\n<\/li>\n<li>\n<p>La pr&eacute;gabaline a &eacute;t&eacute; obtenue ill&eacute;galement dans pr&egrave;s de la moiti&eacute; des cas.<\/p>\n<\/li>\n<li>\n<p>Les principales complications li&eacute;es au m&eacute;susage de la pr&eacute;gabaline sont&nbsp;: coma&#x002C; troubles de la conscience&#x002C; d&eacute;sorientation et confusion; des cas d&#39;insuffisance respiratoire&#x002C; de coma et de d&eacute;c&egrave;s ont &eacute;galement &eacute;t&eacute; rapport&eacute;s. On rapporte souvent un usage concomitant d&rsquo;autres m&eacute;dicaments d&eacute;presseurs du syst&egrave;me nerveux central&#x002C; tels que les opio&iuml;des&#x002C; avec pour cons&eacute;quence que la pr&eacute;gabaline n&rsquo;est fr&eacute;quemment pas la seule cause des effets ind&eacute;sirables. La pr&eacute;gabaline pourrait diminuer le seuil de tol&eacute;rance aux opio&iuml;des&#x002C; ce qui entrainerait un risque augment&eacute; de d&eacute;pression respiratoire et de d&eacute;c&egrave;s li&eacute;s aux opio&iuml;des.<\/p>\n<\/li>\n<\/ul>\n<p><b>En pratique<\/b>&#x002C; le centre belge de pharmacovigilance et le CBIP recommandent&nbsp;:<\/p>\n<ul>\n<li>\n<p>Aux m&eacute;decins d&rsquo;&ecirc;tre particuli&egrave;rement attentifs avant d&rsquo;initier un traitement par pr&eacute;gabaline ou de renouveler une prescription chez un patient qui n&rsquo;est pas r&eacute;guli&egrave;rement suivi par le m&eacute;decin. La prudence est de rigueur en cas d&#39;ant&eacute;c&eacute;dents d&#39;abus de drogues et de m&eacute;dicaments et chez les patients qui prennent aussi d&rsquo;autres&nbsp;d&eacute;presseurs du syst&egrave;me nerveux central&#x002C; tels que les opio&iuml;des.<\/p>\n<\/li>\n<li>\n<p>Aux pharmaciens&#x002C; dans le cadre des soins pharmaceutiques&#x002C; de bien v&eacute;rifier la conformit&eacute; de la prescription et de contacter le prescripteur en cas de doute.<\/p>\n<\/li>\n<li>\n<p>Aux m&eacute;decins et pharmaciens&#x002C; de porter plainte aupr&egrave;s de la police en cas de d&eacute;couverte de fausses prescriptions.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En f&eacute;vrier 2020&#x002C; les Folia attiraient l&rsquo;attention sur le risque  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,31],"tags":[20213,20224],"class_list":["post-186694","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2021-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186694"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186694\/revisions"}],"predecessor-version":[{"id":189251,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186694\/revisions\/189251"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}