{"id":186498,"date":"2023-12-21T00:00:00","date_gmt":"2023-12-20T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/nouveautes-medicaments-decembre-2023\/"},"modified":"2026-07-09T15:11:54","modified_gmt":"2026-07-09T13:11:54","slug":"nouveautes-medicaments-decembre-2023","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/nouveautes-medicaments-decembre-2023\/","title":{"rendered":"Nouveaut\u00e9s m\u00e9dicaments d\u00e9cembre 2023"},"content":{"rendered":"<div class='summary'><span class='new-molecules-small'>&nbsp;<\/span><b>Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e<\/b><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#ela'>&eacute;ladocag&egrave;ne exuparvovec (Upstaza&reg;\u25bc<span class='ot'> <\/span>): d&eacute;ficit en d&eacute;carboxylase d&rsquo;acide L-amin&eacute; aromatique<\/a><br \/> <span class='new-molecules-small'>&nbsp;<\/span><b>Nouveaut&eacute;s hom&eacute;opathiques<\/b><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#ner'>Nervoheel&reg;&nbsp;: nervosit&eacute;&#x002C; troubles du sommeil<\/a><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#zee'>Zeel&reg;&nbsp;: sympt&ocirc;mes li&eacute;s &agrave; l&rsquo;arthrose et aux maladies articulaires rhumatismales<\/a><\/span><\/span><\/span><\/span><br \/> <span class='new-molecules-small'>&nbsp;<\/span><b>Nouvelles indications<\/b><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#olu'>baricitinib (Olumiant&reg;<span class='ot'> <\/span><span class='mp-kidney-m'> <\/span>): dermatite atopique &agrave; partir de l&rsquo;&acirc;ge de 2 ans<\/a><\/span><\/span><br \/> <span class='folia-samenvatting-tekst'><strong><span class='folia-samenvatting-tekst'><\/span><span class='folia-samenvatting-tekst'>Remboursements<\/span><span class='folia-samenvatting-tekst'><\/span><\/strong><span class='folia-samenvatting-tekst'><br \/> &nbsp; &nbsp; &bull; <span class='folia-samenvatting-tekst'><a href='#tez'>t&eacute;z&eacute;pelumab (Tezspire&reg;) : asthme s&eacute;v&egrave;re<\/a><br \/> <span class='folia-samenvatting-tekst'><span class='removed-molecules-small'>&nbsp;<\/span><span class='folia-samenvatting-vet'><b>Arr&ecirc;ts&nbsp;<\/b><\/span><\/span><b>de commercialisation<\/b><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#eth'>&eacute;thinylestradiol 50 &micro;g + l&eacute;vonorgestrel en comprim&eacute;s (Microgynon 50&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#met'>m&eacute;thadone comprim&eacute;s (Mephenon&reg;)<\/a><span class='folia-samenvatting-tekst'><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#pyr'>pyridoxine comprim&eacute;s (Pyridoxine&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#tix'>tixag&eacute;vimab + cilgavimab (Evusheld&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#vin'>vind&eacute;sine (Eldisine&reg;)<\/a><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/div>\n<div class='summary'><span class='folia-samenvatting-tekst'>\u25bc: <\/span>m&eacute;dicaments soumis &agrave; une surveillance particuli&egrave;re et pour lesquels la <a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>notification d<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>&rsquo;<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>effets ind<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>&eacute;<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>sirables<\/a> au Centre Belge de Pharmacovigilance est encourag&eacute;e (entre autres m&eacute;dicaments contenant un nouveau principe actif&#x002C; m&eacute;dicaments biologiques).<br \/> <span class='ot'> <\/span> : m&eacute;dicaments pour lesquels des proc&eacute;dures additionnelles de minimisation des risques (<i>Risk Minimization Activities<\/i>&nbsp;: RMA) ont &eacute;t&eacute; impos&eacute;es par l&rsquo;autorit&eacute; qui d&eacute;livre l&rsquo;autorisation de mise sur le march&eacute; (voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2307?folia=2260'>Folia mars 2015<\/a>)&#x002C; telles que du mat&eacute;riel &eacute;ducatif ou des brochures.<br \/> <span class='mp-kidney-s'> <\/span> contre-indication ou r&eacute;duction de dose en cas d&rsquo;insuffisance r&eacute;nale s&eacute;v&egrave;re (clairance de la cr&eacute;atinine entre 30 et 15 ml\/min).<br \/> <span class='mp-kidney-m'> <\/span> contre-indication ou r&eacute;duction de dose d&eacute;j&agrave; en cas d&rsquo;insuffisance r&eacute;nale mod&eacute;r&eacute;e (clairance de la cr&eacute;atinine inf&eacute;rieure ou &eacute;gale &agrave; 60 ml\/min)&#x002C; ou en cas d&#39;insuffisance r&eacute;nale sans pr&eacute;cision du degr&eacute; de s&eacute;v&eacute;rit&eacute;.<\/div>\n<p>Les actualit&eacute;s m&eacute;dicamenteuses de ce mois prennent en compte les changements port&eacute;s &agrave; notre connaissance jusqu&rsquo;au 24 novembre. Les modifications signal&eacute;es apr&egrave;s cette date seront reprises dans les Weekly Folia du mois de janvier.<br \/> &nbsp;<br \/> Les textes du R&eacute;pertoire concernant ces actualit&eacute;s seront mis &agrave; jour &agrave; la date du 22 d&eacute;cembre.<br \/> &nbsp;<\/p>\n<h2><a class='section' id='new-molecules-small'><span class='new-molecules-small'>&nbsp;<\/span><\/a>Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e<\/h2>\n<h3><a data-type='molecule' id='ela' name='ela'><\/a>&eacute;ladocag&egrave;ne exuparvovec &nbsp;(Upstaza&reg;\u25bc )&nbsp;<\/h3>\n<div class='summary'><b>L&rsquo;&eacute;ladocag&egrave;ne exuparvovec <\/b>(Upstaza<b>&reg;<\/b>\u25bc &#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/21?frag=16477'>chapitre 20.3<\/a>&#x002C; injection intraputaminale&#x002C; usage hospitalier&#x002C; m&eacute;dicament orphelin) a pour indication le d&eacute;ficit en d&eacute;carboxylase d&rsquo;acide L-amin&eacute; aromatique (AADC) associ&eacute; &agrave; un ph&eacute;notype s&eacute;v&egrave;re chez les patients &agrave; partir de 18 mois (synth&egrave;se du RCP).<\/div>\n<ul>\n<li>\n<p>Il s&rsquo;agit d&rsquo;une <b>maladie g&eacute;n&eacute;tique rare<\/b>&#x002C; o&ugrave; le d&eacute;ficit enzymatique emp&ecirc;che la synth&egrave;se de dopamine et de s&eacute;rotonine&#x002C; entrainant un <b>retard de d&eacute;veloppement psychomoteur<\/b> chez les enfants.<\/p>\n<\/li>\n<li>\n<p>L&rsquo;&eacute;ladocag&egrave;ne exuparvovec est le <b>premier traitement<\/b> autoris&eacute; pour cette pathologie. Il s&rsquo;agit d&rsquo;une <b>th&eacute;rapie g&eacute;nique<\/b> par laquelle on introduit le g&egrave;ne codant pour l&rsquo;enzyme AADC humaine d&eacute;ficiente &agrave; l&rsquo;aide d&rsquo;un virus non pathog&egrave;ne pour l&rsquo;humain et non r&eacute;plicant.<\/p>\n<\/li>\n<li>\n<p>Des &eacute;tudes non comparatives chez 21 enfants avec un suivi de maximum 5 ans ont montr&eacute; que 50 &agrave; 70% des enfants pouvaient tenir la t&ecirc;te ou rester assis sans aide&#x002C; 30% pouvaient tenir debout avec aide&#x002C; ce qui n&rsquo;est pas le cas dans le d&eacute;cours naturel de la maladie.<\/p>\n<\/li>\n<li>\n<p>La majorit&eacute; des enfants ont pr&eacute;sent&eacute; des dyskin&eacute;sies pouvant durer plusieurs mois.1&#x002C;2<\/p>\n<\/li>\n<li>\n<p>Du <a href='https:\/\/basededonneesdesmedicaments.be\/medicament\/62fe30ddfea67e0f7c7b8220\/rma'>mat&eacute;riel Risk Minimization Activities<\/a> (RMA ) est &agrave; disposition des professionnels de la sant&eacute;.<br \/> &nbsp;<\/p>\n<\/li>\n<\/ul>\n<p><strong>Co&ucirc;t<\/strong>&nbsp;: 3 500 000&euro; pour un flacon&#x002C; rembours&eacute; en a&nbsp;! au 1<sup>er<\/sup> novembre 2023.<\/p>\n<p> &nbsp;<\/p>\n<h2><a class='section' id='new-molecules-small'><span class='new-molecules-small'>&nbsp;<\/span><\/a>Nouveaut&eacute;s hom&eacute;opathiques<\/h2>\n<h3><a data-type='molecule' id='ner' name='ner'><\/a>Nervoheel&reg;&nbsp;<\/h3>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/21?frag=18671&amp;trade_family=47514'><b>Nervoheel&reg;<\/b><\/a> (comprim&eacute;s) est un m&eacute;dicament <b>hom&eacute;opathique<\/b> qui a pour indications les sympt&ocirc;mes li&eacute;s au stress&#x002C; &agrave; l&rsquo;anxi&eacute;t&eacute; et aux troubles du sommeil (synth&egrave;se du RCP).<span class='folia-referentie-note'>1<\/span><br \/> Le CBIP rappelle qu&beta;e la <b>prise en charge de l&rsquo;anxi&eacute;t&eacute; et des troubles du sommeil<\/b> est en premier lieu <b>non-m&eacute;dicamenteuse<\/b> (<a href='https:\/\/www.cbip.be\/fr\/articles\/3078?folia=3076'>voir Folia juin 2019<\/a>).<br \/> Il n&rsquo;existe &agrave; l&rsquo;heure actuelle aucune preuve valable d&rsquo;efficacit&eacute; des m&eacute;dicaments hom&eacute;opathiques par rapport au placebo [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/1865?folia=1856'>Folia de novembre 2010<\/a> et <a href='https:\/\/www.cbip.be\/fr\/articles\/2824?folia=2820'>Folia de janvier 2018<\/a>]. Les exigences en mati&egrave;re d&rsquo;efficacit&eacute; et de s&eacute;curit&eacute; dans le cadre de l&rsquo;autorisation d&rsquo;un m&eacute;dicament hom&eacute;opathique sont beaucoup plus limit&eacute;es que pour les m&eacute;dicaments classiques.<\/p>\n<p> <strong>Co&ucirc;t<\/strong>&nbsp;: 24&#x002C;95&euro; pour 100 comprim&eacute;s&#x002C; 44&#x002C;95&euro; pour 250 comprim&eacute;s&#x002C; non rembours&eacute; au 1<sup>er<\/sup> d&eacute;cembre 2023.<\/p>\n<p> &nbsp;<\/p>\n<h3><a data-type='molecule' id='zee' name='zee'><\/a>Zeel&reg;&nbsp;<\/h3>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/21?frag=18671&amp;trade_family=47522'><b>Zeel&reg;<\/b><\/a> (solution pour injection i.m.&#x002C; s.c.&#x002C; i.derm. et i.artic.) est un m&eacute;dicament <b>hom&eacute;opathique<\/b> qui a pour indications les sympt&ocirc;mes d&rsquo;arthrose et de maladie articulaire rhumatismale (synth&egrave;se du RCP).<span class='folia-referentie-note'>1<\/span><br \/> Il n&rsquo;existe &agrave; l&rsquo;heure actuelle aucune preuve valable d&rsquo;efficacit&eacute; des m&eacute;dicaments hom&eacute;opathiques par rapport au placebo [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/1865?folia=1856'>Folia de novembre 2010<\/a> et <a href='https:\/\/www.cbip.be\/fr\/articles\/2824?folia=2820'>Folia de janvier 2018<\/a>]. Les exigences en mati&egrave;re d&rsquo;efficacit&eacute; et de s&eacute;curit&eacute; dans le cadre de l&rsquo;autorisation d&rsquo;un m&eacute;dicament hom&eacute;opathique sont beaucoup plus limit&eacute;es que pour les m&eacute;dicaments classiques.<\/p>\n<p> <b>Co&ucirc;t<\/b>&nbsp;: 44&#x002C;95&euro; pour 10 flacons de 2 ml&#x002C; 299&#x002C;95&euro; pour 100 flacons&#x002C; non rembours&eacute; au 1<sup>er<\/sup> d&eacute;cembre 2023.<\/p>\n<p> \u200b<\/p>\n<h2><a class='section' id='new-molecules-small'><span class='new-molecules-small'>&nbsp;<\/span><\/a>Nouvelles indications<\/h2>\n<h3><a data-type='molecule' id='olu' name='olu'><\/a>baricitinib (Olumiant&reg;<span class='ot'> <\/span><span class='mp-kidney-m'> <\/span>)<\/h3>\n<p>Le <a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=28407'><b>baricitinib<\/b><\/a> (Olumiant<b>&reg;<span class='ot'> <\/span><span class='mp-kidney-m'> <\/span><\/b>&#x002C; administration orale)&#x002C; un <a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=28506'>inhibiteur de Janus kinases<\/a> d&eacute;j&agrave; autoris&eacute; dans la <strong>dermatite atopique<\/strong> de l&rsquo;adulte&#x002C; a maintenant pour indication la <strong>dermatite atopique mod&eacute;r&eacute;e &agrave; s&eacute;v&egrave;re<\/strong> chez les <strong>enfants &agrave; partir de l&rsquo;&acirc;ge de 2 ans<\/strong> (synth&egrave;se du RCP).<br \/> Il avait aussi comme indications chez l&rsquo;adulte la polyarthrite rhumato&iuml;de&#x002C; la dermatite atopique et la pelade&#x002C; et chez l&rsquo;enfant l&rsquo;arthrite idiopathique juv&eacute;nile.<br \/> Le dossier d&rsquo;enregistrement mentionne une &eacute;tude chez 482 enfants &acirc;g&eacute;s de 2 &agrave; 18 ans (&acirc;ge moyen 12 ans) non contr&ocirc;l&eacute;s sous corticost&eacute;ro&iuml;des topiques (score vIGA-AD de 3 ou 4 sur un total de 4). Le baricitinib (4 mg de 10 &agrave; 18 ans&#x002C; et 2 mg de 2 &agrave; 9 ans) a &eacute;t&eacute; plus efficace que le placebo &agrave; 16 semaines pour obtenir une score vIGA-AD de 0 ou 1&#x002C; avec une am&eacute;lioration d&rsquo;au moins 2 points (crit&egrave;re primaire). Les r&eacute;sultats concernant le baricitinib 1 mg n&rsquo;ont pas &eacute;t&eacute; statistiquement significatifs.<span class='folia-referentie-note'>1&#x002C;2<\/span><br \/> Le RCP mentionne un profil d&rsquo;innocuit&eacute; similaire &agrave; celui des adultes concernant les effets ind&eacute;sirables fr&eacute;quents&#x002C; avec cependant <b>plus de neutrop&eacute;nies<\/b> que chez les adultes (1&#x002C;7%)&#x002C; sans r&eacute;percussion sur le nombre d&rsquo;infections s&eacute;v&egrave;res.<br \/> Les inhibiteurs de <b>Janus kinases<\/b> peuvent causer des <b>effets ind&eacute;sirables graves<\/b> et ne peuvent &ecirc;tre <b>prescrits <\/b>dans les maladies inflammatoires <b>que dans des conditions strictes<\/b> (<a href='https:\/\/www.cbip.be\/fr\/articles\/3962?folia=3941'>voir Folia de d&eacute;cembre 2022<\/a>).<br \/> En cas de r&eacute;ponse satisfaisante&#x002C; la posologie peut &ecirc;tre diminu&eacute;e de moiti&eacute;. Ceci peut poser probl&egrave;me si une dose de 1 mg est indiqu&eacute;e&nbsp;: les comprim&eacute;s de 2 mg ne sont pas s&eacute;cables&#x002C; et les comprim&eacute;s de 1 mg ne sont pas disponibles sur le march&eacute; belge (situation au 1<sup>er<\/sup> d&eacute;cembre 2023).<span class='folia-referentie-note'>3<\/span><\/p>\n<p> <strong>Posologie<\/strong>&nbsp;: 1 comprim&eacute; de 2 ou 4 mg une fois p.j. en fonction du poids.<\/p>\n<p> <strong>Co&ucirc;t<\/strong>&nbsp;: 2399&#x002C;20&euro; pour 84 jours de traitement&#x002C; non rembours&eacute; dans l&rsquo;indication dermatite atopique chez&nbsp; l&rsquo;enfant au 1<sup>er<\/sup>&nbsp;d&eacute;cembre&nbsp;2023. Le baricitinib est rembours&eacute; en <span class='ssecr-b4'> <\/span>uniquement chez l&rsquo;adulte dans la polyarthrite rhumato&iuml;de et la dermatite atopique (<a href='https:\/\/www.cbip.be\/fr\/ampps\/153171?cat=b'>voir conditions et formulaires<\/a>).<\/p>\n<p> &nbsp;<\/p>\n<h2><a class='section' id='andere'><\/a>Remboursements<\/h2>\n<h3><a data-type='molecule' id='tez' name='tez'><\/a>t&eacute;z&eacute;pelumab (Tezspire&reg;)<\/h3>\n<p>Le <a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8903890&amp;view=pvt&amp;vmp_group=47159'><strong>t&eacute;z&eacute;pelumab<\/strong><\/a> (Tezspire&reg;)&#x002C; un anticorps monoclonal utilis&eacute; dans le traitement de l&rsquo;asthme (<a href='https:\/\/www.cbip.be\/fr\/articles\/query?number=F50F03J#tez'>voir Nouveaut&eacute;s m&eacute;dicaments mars 2023<\/a><a>)<\/a>&#x002C; est maintenant <strong>rembours&eacute; <\/strong>en <span class='ssecr-b4'> <\/span>comme <b>traitement additionnel de l&rsquo;asthme s&eacute;v&egrave;re<\/b> inflammatoire de type 2 chez les <b>adultes<\/b> <b>insuffisamment contr&ocirc;l&eacute;s<\/b> par un corticost&eacute;ro&iuml;de inhal&eacute; (CSI) &agrave; dose &eacute;lev&eacute;e associ&eacute; &agrave; un autre traitement de l&rsquo;asthme.<br \/> La demande doit &ecirc;tre faite par un pneumologue. Pour le d&eacute;tail des conditions et les formulaires de demande&#x002C; cliquer sur le sigle <span class='ssecr-b4'> <\/span>au niveau de la sp&eacute;cialit&eacute; dans le R&eacute;pertoire.<\/p>\n<div class='detailed-content'>Les conditions de remboursement comprennent&#x002C; entre-autres <\/p>\n<ul>\n<li>La v&eacute;rification de l&rsquo;observance au traitement et de la technique d&rsquo;inhalation&#x002C; notamment via des entretiens d&rsquo;accompagnement au Bon Usage des M&eacute;dicaments r&eacute;alis&eacute;s par un pharmacien&#x002C; infirmi&egrave;(re) ou kin&eacute;sith&eacute;rapeute.<\/li>\n<li>Avoir recherch&eacute; une exposition aux allerg&egrave;nes&#x002C; tabagisme&#x002C; et trait&eacute; les comorbidit&eacute;s aggravantes.<\/li>\n<li>&Ecirc;tre trait&eacute; par CSI + un autre traitement de l&rsquo;asthme.<\/li>\n<li>Avoir pr&eacute;sent&eacute; au cours des 12 derniers mois\n<ul>\n<li>VEMS &lt; 80%<\/li>\n<li>Taux sanguin d&rsquo;&eacute;osinophiles &ge; 150\/&micro;L + concentration de FeNO &ge; 25 ppb<\/li>\n<li>Au moins 2 hospitalisations ou recours aux urgences pour asthme s&eacute;v&egrave;re&#x002C; ou 2 exacerbations&#x002C; ou &ecirc;tre corticod&eacute;pendant (aux corticost&eacute;ro&iuml;des oraux).<\/li>\n<\/ul>\n<\/li>\n<\/ul><\/div>\n<p><b>Co&ucirc;t<\/b>&nbsp;: 1176&#x002C;20&euro; pour une injection mensuelle&#x002C; rembours&eacute; en <span class='ssecr-b4'> <\/span>au 1er d&eacute;cembre 2023<\/p>\n<p> &nbsp;<\/p>\n<h2><a class='section' id='removed-molecules-small'><span class='removed-molecules-small'>&nbsp;<\/span><\/a>Arr&ecirc;ts de commercialisation<\/h2>\n<p>Cette rubrique concerne les arr&ecirc;ts d&eacute;finitifs de commercialisation. Les sp&eacute;cialit&eacute;s concern&eacute;es ne sont plus mentionn&eacute;es dans le R&eacute;pertoire.<br \/> La liste des m&eacute;dicaments indisponibles peut &ecirc;tre consult&eacute;e sur le <a href='https:\/\/www.pharmastatut.be\/'>site de l&rsquo;AFMPS-Pharmastatut<\/a><a>.<\/a><br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='eth' name='eth'><\/a>&eacute;thinylestradiol 50 &micro;g + l&eacute;vonorgestrel en comprim&eacute;s (Microgynon 50&reg;)<\/h3>\n<p>L&rsquo;association <strong>&eacute;thinylestradiol 50 &micro;g + l&eacute;vonorgestrel<\/strong> en comprim&eacute;s pour la contraception (Microgynon 50&reg;) n&rsquo;est <strong>plus commercialis&eacute;e<\/strong>. Il n&rsquo;existe plus de pr&eacute;paration monophasique de 1<sup>&egrave;re<\/sup> g&eacute;n&eacute;ration&#x002C; c&rsquo;est-&agrave;-dire avec dose &eacute;lev&eacute;e d&rsquo;estrog&egrave;nes. Il n&rsquo;existe <strong>pas d&rsquo;alternative<\/strong> pour les femmes qui utilisaient ce type de pr&eacute;paration. Quand une <strong>association estroprogestative<\/strong> est souhait&eacute;e <strong>comme contraceptif<\/strong>&#x002C; et en l&rsquo;absence de contre-indications&#x002C; les <a href='https:\/\/www.cbip.be\/fr\/chapters\/7?frag=5348'><strong>pr&eacute;parations monophasiques de 2<\/strong><\/a><a href='https:\/\/www.cbip.be\/fr\/chapters\/7?frag=5348'><strong><sup>&egrave;me<\/sup><\/strong><\/a><a href='https:\/\/www.cbip.be\/fr\/chapters\/7?frag=5348'><strong> g&eacute;n&eacute;ration<\/strong><\/a> (oestrog&egrave;nes &agrave; 20 ou 30 &micro;g) ont le <strong>meilleur rapport b&eacute;n&eacute;fice-risque<\/strong> (<a href='https:\/\/www.cbip.be\/fr\/chapters\/7?frag=5306'>voir aussi 6.2. Contraception<\/a>).<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='met' name='met'><\/a>m&eacute;thadone comprim&eacute;s (Mephenon&reg;)<\/h3>\n<p>La <b>m&eacute;thadone en comprim&eacute;s<\/b> (Mephenon&reg;) n&rsquo;est <b>plus commercialis&eacute;e<\/b>. Il reste la forme injectable (<a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=6668&amp;trade_family=16642'>Mephenon&reg;<span class='mp-dop'><\/span><span class='mp-kidney-s'> <\/span><\/a>).<br \/> Pour la prise en charge des douleurs n&eacute;cessitant un opio&iuml;de&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=6551'>d&rsquo;autres opio&iuml;des<\/a> sont disponibles.<br \/> Pour la <a href='https:\/\/www.cbip.be\/fr\/chapters\/11?frag=8466'>th&eacute;rapie de substitution des patients d&eacute;pendants aux opio&iuml;des<\/a>&#x002C;&nbsp;la m&eacute;thadone reste <strong>disponible en tant que mati&egrave;re premi&egrave;re<\/strong> pour la pr&eacute;paration de g&eacute;lules ou de sirops.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='pyr' name='pyr'><\/a>pyridoxine comprim&eacute;s (Pyridoxine&reg;)<\/h3>\n<p>La <strong>pyridoxine en monopr&eacute;paration en comprim&eacute;s<\/strong> (vitamine B6&#x002C; Pyridoxine&reg;) n&rsquo;est <strong>plus commercialis&eacute;e<\/strong>. Elle existe encore sous forme injectable (<a href='https:\/\/www.cbip.be\/fr\/chapters\/15?frag=13524&amp;trade_family=29124'>Vitamine B6 Sterop&reg;<\/a>)&#x002C; et au <strong>m&ecirc;me<\/strong> <strong>dosage<\/strong> (250 mg) <strong>dans une association de vitamines B<\/strong> (<a href='https:\/\/www.cbip.be\/fr\/chapters\/15?frag=18200&amp;trade_family=31757'>Befact&reg;<\/a>). La pyridoxine est indiqu&eacute;e chez les <strong>patients d&eacute;pendants &agrave; l&#39;alcool<\/strong>&#x002C; en cas de traitement chronique par l&rsquo;isoniazide ou dans certaines maladies m&eacute;taboliques du nourrisson.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='tix' name='tix'><\/a>tixag&eacute;vimab + cilgavimab (Evusheld)<\/h3>\n<p>L&rsquo;association <b>tixag&eacute;vimab + cilgavimab<\/b> (Evusheld&reg;) n&rsquo;est <b>plus commercialis&eacute;e<\/b>. Elle &eacute;tait utilis&eacute;e pour la <b>prophylaxie pr&eacute;-exposition au COVID-19 et pour le traitement des patients &agrave; risque de d&eacute;velopper une forme s&eacute;v&egrave;re<\/b>&#x002C; mais n&rsquo;&eacute;tait <b>plus recommand&eacute;e<\/b> en raison d&rsquo;un manque d&rsquo;efficacit&eacute; sur les variants circulant actuellement (voir <a href='https:\/\/kce.fgov.be\/sites\/default\/files\/2023-03\/COVID-19_InterimGuidelines_Treatment_ENG.pdf'>Interim clinical guidance for adults with confirmed COVID-19 in Belgium&#x002C; version 37&#x002C; November 2023<\/a>).<br \/> Pour la pr&eacute;vention du COVID-19 chez les personnes &agrave; risque&#x002C; la <strong>vaccination<\/strong> est la <strong>strat&eacute;gie recommand&eacute;e<\/strong> (<a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8901373'>voir 12.1.1.15. Vaccin contre le COVID-19<\/a>&#x002C;&nbsp;et <a href='https:\/\/www.cbip.be\/fr\/articles\/4146?folia=4143'>Folia ao&ucirc;t 2023<\/a>).<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='vin' name='vin'><\/a>vind&eacute;sine (Eldisine&reg;)<\/h3>\n<p>La vind&eacute;sine (Eldisine&reg;)&#x002C; un antitumoral utilis&eacute; dans certaines h&eacute;mopathies malignes ou certaines tumeurs mammaires ou pulmonaires&#x002C; n&rsquo;est plus commercialis&eacute;e.<\/p>\n<p> &nbsp;<\/p>\n<h2>Sources<\/h2>\n<p>En plus des sources g&eacute;n&eacute;rales consult&eacute;es syst&eacute;matiquement par le CBIP (British Medical Journal&#x002C; New England Journal of Medicine&#x002C; Annals of Internal Medicine&#x002C; The Lancet&#x002C; JAMA&#x002C; Drug &amp; Therapeutic Bulletin&#x002C; GeBu&#x002C; La Revue Prescrire&#x002C; Australian Prescriber)&#x002C; pour &eacute;crire les articles &laquo;&nbsp;nouveaut&eacute;s m&eacute;dicamenteuses&nbsp;&raquo;&#x002C; les sources suivantes sont consult&eacute;es : RCP et dossier d&rsquo;&eacute;valuation &agrave; l&rsquo;EMA (EPAR) du produit&#x002C; The Medical Letter&#x002C; NEJM Journal Watch.<\/p>\n<p>&nbsp;<\/p>\n<h2>Sources sp&eacute;cifiques<\/h2>\n<h3>baricitinib<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> <a href='https:\/\/www.ema.europa.eu\/en\/documents\/variation-report\/olumiant-h-c-004085-ii-0037-epar-assessment-report-variation_en.pdf'>Olumiant-Assessment Report. EMA\/436396\/2023 Committee for Medicinal Products for Human Use (CHMP) 14 September 2023<\/a><\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>2<\/span> Efficacy and safety of baricitinib in combination with topical corticosteroids in paediatric patients with moderate-to-severe atopic dermatitis with an inadequate response to topical corticosteroids: results from a phase III&#x002C; randomized&#x002C; double-blind&#x002C; placebo-controlled study (BREEZE-AD PEDS). Antonio Torrelo et al. B<em>r J Dermatol<\/em> 2023; <strong>189<\/strong>:23&ndash;32<\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>3<\/span> Olumiant&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit<\/span><br \/> &nbsp;<\/p>\n<h3>Nervoheel&reg;<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Nervoheel&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit<span class='folia-referentie-tekst'><\/span><\/span><br \/> &nbsp;<\/p>\n<h3>Zeel&reg;<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Zeel&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit<\/span><br \/> &nbsp;<\/p>\n<h3>&eacute;ladocag&egrave;ne exuparvovec<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Upstaza&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit<\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>2<\/span> &Eacute;ladocag&egrave;ne exuparvovec (Upstaza&deg;) et d&eacute;ficit en d&eacute;carboxylase d&#39;acide L-amin&eacute; aromatique. Rev Prescrire 2023 ; 43 (480) : 739-740<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e &nbsp; &nbsp; &bull; &eacute;ladocag&egrave;ne exuparvovec (Upstaza&reg;\u25bc  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186498","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186498"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186498\/revisions"}],"predecessor-version":[{"id":189055,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186498\/revisions\/189055"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}