{"id":175509,"date":"2020-07-14T00:00:00","date_gmt":"2020-07-13T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/nouveau-type-de-learning-dans-notre-auditorium-le-quiz-medication\/"},"modified":"2026-05-07T19:11:52","modified_gmt":"2026-05-07T17:11:52","slug":"nouveau-type-de-learning-dans-notre-auditorium-le-quiz-medication","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/nouveau-type-de-learning-dans-notre-auditorium-le-quiz-medication\/","title":{"rendered":"Nouveau type d&rsquo;e-learning dans notre Auditorium : le Quiz M\u00e9dication"},"content":{"rendered":"<p>Sur notre <a href='https:\/\/www.cbip.be\/fr\/auditorium'>Auditorium<\/a>&#x002C; la plateforme d&#39;apprentissage en ligne du CBIP&#x002C; vous pouvez d&eacute;sormais vous mettre au d&eacute;fi et tester vos connaissances en mati&egrave;re de m&eacute;dication &agrave; partir d&rsquo;&eacute;tudes de cas tir&eacute;s de la pratique. Les &eacute;tudes de cas ont &eacute;t&eacute; d&eacute;velopp&eacute;es par la <em>British Pharmacological Society<\/em> et adapt&eacute;es au contexte belge par le CBIP.<br \/> Gr&acirc;ce au Quiz M&eacute;dication&#x002C; vous renforcerez vos connaissances sur la m&eacute;dication et la prescription s&ucirc;re. Reconnaissez-vous cet effet ind&eacute;sirable ? &Agrave; quelle interaction devez-vous faire attention ? Comment assurer le suivi de ce m&eacute;dicament ? Et que dites-vous &agrave; votre patient ? Des questions pertinentes vous seront soumises concernant des m&eacute;dicaments couramment utilis&eacute;s et des pathologies communes. Si la r&eacute;ponse ne vous vient pas tout de suite&#x002C; vous pouvez lancer une recherche dans le R&eacute;pertoire en cliquant sur les liens correspondants.<br \/> Un nouveau Quiz M&eacute;dication sera publi&eacute; plusieurs fois par an.<br \/> Les e-learning sont gratuits. Une fois inscrit&#x002C; vous avez acc&egrave;s &agrave; tous les modules. Si vous r&eacute;ussissez&#x002C; en tant que m&eacute;decin ou pharmacien&#x002C; vous obtenez une accr&eacute;ditation.<br \/> D&eacute;couvrez d&egrave;s maintenant dans notre Auditorium <a href='https:\/\/auditorium.flowsparks.com\/?startactivity=MQZ20'>le premier Quiz M&eacute;dication&#x002C; &eacute;dition &eacute;t&eacute; 2020<\/a>. Dur&eacute;e totale : 30 minutes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur notre Auditorium&#x002C; la plateforme d&#39;apprentissage en ligne du CBIP&#x002C;  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,61],"tags":[20213,20224],"class_list":["post-175509","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2020-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=175509"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175509\/revisions"}],"predecessor-version":[{"id":178091,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175509\/revisions\/178091"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=175509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=175509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=175509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}