{"id":175495,"date":"2020-11-03T00:00:00","date_gmt":"2020-11-02T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/le-controle-de-lhypertension-arterielle-chez-les-personnes-agees-adaptations-dans-le-formulaire-de-soins-aux-personnes-agees\/"},"modified":"2026-05-07T19:11:51","modified_gmt":"2026-05-07T17:11:51","slug":"le-controle-de-lhypertension-arterielle-chez-les-personnes-agees-adaptations-dans-le-formulaire-de-soins-aux-personnes-agees","status":"publish","type":"post","link":"https:\/\/cbip.be\/fr\/le-controle-de-lhypertension-arterielle-chez-les-personnes-agees-adaptations-dans-le-formulaire-de-soins-aux-personnes-agees\/","title":{"rendered":"Le contr\u00f4le de l\u2019hypertension art\u00e9rielle chez les personnes \u00e2g\u00e9es \u2013 Adaptations dans le Formulaire de soins aux Personnes Ag\u00e9es"},"content":{"rendered":"<div class='summary'>Chez les personnes tr&egrave;s &acirc;g&eacute;es (&ge;80 ans) et les personnes &acirc;g&eacute;es (&ge;65 ans)&#x002C; il n&rsquo;y a pas d&rsquo;unanimit&eacute; quant aux valeurs seuils et cibles de pression art&eacute;rielle. Sur base de deux &eacute;tudes &eacute;pid&eacute;miologiques publi&eacute;es en 2018&#x002C; &eacute;valuant l&rsquo;association entre la pression art&eacute;rielle et la morbi-mortalit&eacute; chez les personnes &acirc;g&eacute;es&#x002C; et les recommandations internationales r&eacute;centes&#x002C; la r&eacute;daction du Formulaire de soins aux Personnes &Acirc;g&eacute;es propose: <\/p>\n<ol>\n<li>\n<p>de ne pas initier un traitement si le patient a une tension systolique inf&eacute;rieure &agrave; 150-160 mmHg (selon l&rsquo;&eacute;tat de sant&eacute; global du patient)<\/p>\n<\/li>\n<li>\n<p>de maintenir la prudence et avoir comme cible th&eacute;rapeutique une tension systolique inf&eacute;rieure &agrave; 140-150 mmHg et de ne viser des valeurs plus basses que si le traitement est bien tol&eacute;r&eacute;<\/p>\n<\/li>\n<\/ol><\/div>\n<h2>Contexte<\/h2>\n<p>Chez les personnes &acirc;g&eacute;es et surtout chez les tr&egrave;s &acirc;g&eacute;es&#x002C; il n&rsquo;y a pas d&rsquo;unanimit&eacute; quant aux valeurs seuils et les valeurs cibles de pression art&eacute;rielle. Les sujets les plus vuln&eacute;rables avec des comorbidit&eacute;s&#x002C; et donc souvent la population &acirc;g&eacute;e&#x002C; sont tr&egrave;s peu repr&eacute;sent&eacute;s dans les &eacute;tudes ce qui limite les donn&eacute;es probantes et l&rsquo;applicabilit&eacute; des r&eacute;sultats &agrave; cette population. Ainsi&#x002C; les r&eacute;sultats des &eacute;tudes men&eacute;es dans la population g&eacute;n&eacute;rale&#x002C; qui relatent des associations statistiquement significatives entre la diminution de la pression art&eacute;rielle et les &eacute;v&egrave;nements cardiovasculaires doivent &ecirc;tre interpr&eacute;t&eacute;s avec prudence chez les personnes &acirc;g&eacute;es (Voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2852?folia=2845'>Folia de Mars 2018<\/a>).<\/p>\n<h2> Etudes chez des patients &acirc;g&eacute;s<\/h2>\n<p>Deux &eacute;tudes &eacute;pid&eacute;miologiques publi&eacute;es en 2018 &eacute;valuent l&rsquo;association entre la pression art&eacute;rielle et la morbi-mortalit&eacute; chez les personnes tr&egrave;s &acirc;g&eacute;es.<br \/> La premi&egrave;re<span class='folia-referentie-note'>1<\/span> est une &eacute;tude observationnelle prospective qui s&rsquo;est d&eacute;roul&eacute;e pendant trois ans en Chine chez 4.658 individus avec une moyenne d&rsquo;&acirc;ge de 92&#x002C;1 ans et qui &eacute;value l&rsquo;association entre la pression art&eacute;rielle et la mortalit&eacute; (toutes causes et sp&eacute;cifique). On observe une courbe en forme de U entre la pression art&eacute;rielle systolique et le risque de mortalit&eacute;. La pression art&eacute;rielle associ&eacute;e au risque le plus faible est de 129 mmHg. Un risque plus &eacute;lev&eacute;&nbsp;est observ&eacute; avec une pression inf&eacute;rieure &agrave; 107 mmHg (mortalit&eacute; non cardiovasculaire) ou sup&eacute;rieure &agrave; 154 mmHg (mortalit&eacute; cardiovasculaire).<br \/> La seconde &eacute;tude<span class='folia-referentie-note'>2<\/span>&#x002C; observationnelle prospective &eacute;galement&#x002C; &eacute;tudie l&rsquo;association entre la pression art&eacute;rielle systolique et la mortalit&eacute; toutes causes d&rsquo;une part&#x002C; et le d&eacute;clin cognitif (&eacute;valu&eacute; par le <em>Mini-Mental State Examination &ndash; <\/em>MMSE) d&rsquo;autre part&#x002C; dans une population de 570 personnes &acirc;g&eacute;s de 85 ans. La tension art&eacute;rielle systolique moyenne de d&eacute;part &eacute;tait de 155 mmHg. Parmi ces patients&#x002C; 249 (44 %) recevaient un traitement antihypertenseur. La mortalit&eacute; toutes causes &eacute;tait plus &eacute;lev&eacute;e chez ces derniers et augmentait de 29% pour chaque abaissement de 10 mm Hg de la pression art&eacute;rielle systolique (p &lt; 0.001). Le d&eacute;clin cognitif a suivi la m&ecirc;me tendance d&eacute;favorable&#x002C; avec une baisse annuelle du MMSE de -0.35 points (p = 0.004) pour chaque r&eacute;duction de 10 mmHg de pression art&eacute;rielle systolique. Chez les personnes qui ne recevaient pas de traitement antihypertenseur&#x002C; aucune association statistiquement significative entre la pression art&eacute;rielle systolique et la mortalit&eacute; ou le d&eacute;clin cognitif a &eacute;t&eacute; retrouv&eacute;e.<\/p>\n<h2> Discussion critique<\/h2>\n<h3>Valeurs seuils<\/h3>\n<p>Les r&eacute;visions des directives de l&rsquo;American College of Cardiology\/American Heart Association (ACC\/AHA&#x002C; en 2017)<span class='folia-referentie-note'>3<\/span>&#x002C; de l&rsquo;European Society of Cardiology\/European Society of Hypertension (ESC\/ESH en 2018)<span class='folia-referentie-note'>4<\/span>&nbsp;et du National Institute for Health and Care Excellence (NICE&#x002C; en 2019)<span class='folia-referentie-note'>5<\/span>&nbsp;concernant l&rsquo;hypertension n&rsquo;&eacute;tablissent plus de seuil sp&eacute;cifique pour les personnes &acirc;g&eacute;es et les incluent dans les recommandations g&eacute;n&eacute;rales. La directive europ&eacute;enne concernant le traitement de l&rsquo;hypertension&#x002C; d&eacute;crite dans le <a href='https:\/\/www.cbip.be\/fr\/articles\/3024?folia=3022'>Folia de Mars de 2019<\/a> recommande&#x002C; cependant&#x002C; de ne pas entamer un traitement chez les personnes &acirc;g&eacute;es de plus de 80 ans si la valeur de la tension art&eacute;rielle systolique n&rsquo;atteint pas les 160 mmHg. La directive de NICE place ce seuil &agrave; 150 mmHg si la personne ne pr&eacute;sente pas un profil fragile. Le <a href='https:\/\/farmaka.cbip.be\/fr\/formulaire-p-a\/357#main'>Formulaire de Soins aux Personnes &Acirc;g&eacute;es<\/a> s&rsquo;adapte &agrave; ces nouvelles donn&eacute;es et prend en compte l&rsquo;&eacute;tat de sant&eacute; global de l&rsquo;individu et la balance b&eacute;n&eacute;fice\/risque d&rsquo;instaurer un traitement.<\/p>\n<h3>Valeurs cibles<\/h3>\n<p>Le Formulaire &eacute;tablit &eacute;galement des valeurs-cibles &agrave; atteindre dans le contr&ocirc;le tensionnel qui se rapprochent de celles propos&eacute;es par la directive europ&eacute;enne. Celle-ci recommande comme objectif du traitement une tension systolique de 130-139 mmHg pour la plupart des patients&#x002C; m&ecirc;me chez les personnes &acirc;g&eacute;es (65+ et m&ecirc;me 80+)&#x002C; si le traitement est bien tol&eacute;r&eacute;. Le Formulaire reste prudent et s&rsquo;aligne sur la directive de NICE qui &eacute;l&egrave;ve la cible (&lt; 145\/85 mmHg) pour ce groupe d&rsquo;&acirc;ge et rappelle le besoin d&rsquo;&eacute;valuer l&rsquo;individu dans sa globalit&eacute; pour d&eacute;cider si cette cible est la plus ad&eacute;quate. Les deux &eacute;tudes observationnelles pr&eacute;sent&eacute;es<span class='folia-referentie-note'>1&#x002C;2<\/span>&nbsp;confirment ce message de prudence chez le sujet tr&egrave;s &acirc;g&eacute;. En effet&#x002C; il semble qu&rsquo;une descente trop accentu&eacute;e de la pression art&eacute;rielle par le traitement antihypertenseur pourrait &ecirc;tre associ&eacute;e &agrave; une augmentation de la mortalit&eacute; globale et &agrave; une acc&eacute;l&eacute;ration du d&eacute;clin cognitif. Cependant&#x002C; il n&rsquo;est pas possible d&rsquo;&eacute;tablir un lien causal car d&rsquo;autres facteurs confondants peuvent contribuer &agrave; ces r&eacute;sultats (pr&eacute;sence de comorbidit&eacute;s&#x002C; fragilit&eacute;). Des effets ind&eacute;sirables&#x002C; comme la syncope ou l&rsquo;hypotension&#x002C; ont &eacute;t&eacute; associ&eacute;s &agrave; un traitement antihypertenseur plus intensif dans une autre &eacute;tude<span class='folia-referentie-note'>6<\/span>. Ainsi&#x002C; la prise en charge th&eacute;rapeutique de la personne &acirc;g&eacute;e doit &ecirc;tre adapt&eacute;e et proportionn&eacute;e.<\/p>\n<h2> Sources sp&eacute;cifiques<\/h2>\n<p> <span class='folia-referentie-tekst'><span class='folia-referentie-titel'><span class='folia-referentie-nummer'>1.<\/span>&nbsp;<\/span> Lv YB&#x002C; Gao X&#x002C; Yin ZX&#x002C; Chen HS&#x002C; Luo JS&#x002C; et al. Revisiting the association of blood pressure with mortality in oldest people in China: community based&#x002C; longitudinal prospective study. <i>BMJ<\/i>. 2018;361:k2158. doi: <a href='https:\/\/doi.org\/10.1136\/bmj.k2158' target='_blank'>10.1136\/bmj.k2158<\/a><br \/> <span class='folia-referentie-nummer'><span class='folia-referentie-titel'>2.<\/span><\/span>&nbsp;&nbsp;Streit S&#x002C; Poortvliet RKE&#x002C; Gussekloo J. Lower blood pressure during antihypertensive treatment is associated with higher all-cause mortality and accelerated cognitive decline in the oldest-old. Data from the Leiden 85-plus Study. <i>Age Ageing<\/i>. 2018;47:545-50. doi: <a href='https:\/\/doi.org\/10.1093\/ageing\/afy072' target='_blank'>10.1093\/ageing\/afy072<\/a>&nbsp;<br \/> <span class='folia-referentie-nummer'>3.<\/span>&nbsp;&nbsp;2017 ACC\/AHA\/AAPA\/ABC\/ACPM\/AGS\/APhA\/ASH\/ASPC\/NMA\/PCNA Guideline for the Prevention&#x002C; Detection&#x002C; Evaluation&#x002C; and Management of High Blood Pressure in Adults. Via&nbsp;<a href='https:\/\/www.ahajournals.org\/lookup\/doi\/10.1161\/HYP.0000000000000065'>https:\/\/www.ahajournals.org\/lookup\/doi\/10.1161\/HYP.0000000000000065<\/a><br \/> <span class='folia-referentie-titel'><span class='folia-referentie-nummer'>4.<\/span>&nbsp;<\/span> 2018 ESC\/ESH Guidelines for the management of arterial hypertension. Via:&nbsp;<a href='https:\/\/www.escardio.org\/Guidelines\/Clinical-Practice-Guidelines\/Arterial-Hypertension-Management-of'>https:\/\/www.escardio.org\/Guidelines\/Clinical-Practice-Guidelines\/Arterial-Hypertension-Management-of<\/a>. (doi:&nbsp;<a href='https:\/\/doi.org\/10.1093\/eurheartj\/ehy339'>10.1093\/eurheartj\/ehy339<\/a>)<br \/> <span class='folia-referentie-nummer'><span class='folia-referentie-titel'>5.<\/span><\/span>&nbsp;&nbsp;National Insitute for Health and Care Excellence. Hypertension in adults: diagnosis and management. NICE Guideline NG 136. Published date: 28 August 2019. <a href='https:\/\/www.nice.org.uk\/guidance\/ng136'>https:\/\/www.nice.org.uk\/guidance\/ng136<\/a><br \/> <span class='folia-referentie-nummer'><span class='folia-referentie-titel'>6.<\/span><\/span>&nbsp;&nbsp;Sink KM&#x002C; Evans GW&#x002C; Shorr RI&#x002C; Bates JT&#x002C; Berlowitz D et al. Syncope&#x002C; Hypotension&#x002C; and Falls in the Treatment of Hypertension: Results from the Randomized Clinical Systolic Blood Pressure Intervention Trial. <i>J Am Geriatr Soc<\/i>. 2018;66:679-86. doi: <a href='https:\/\/doi.org\/10.1111\/jgs.15236' target='_blank'>10.1111\/jgs.15236<\/a>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez les personnes tr&egrave;s &acirc;g&eacute;es (&ge;80 ans) et les personnes  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,61],"tags":[20213,20224],"class_list":["post-175495","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2020-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=175495"}],"version-history":[{"count":1,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175495\/revisions"}],"predecessor-version":[{"id":178077,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/posts\/175495\/revisions\/178077"}],"wp:attachment":[{"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=175495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=175495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=175495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}